{"id":2531,"count":1,"description":"","link":"https:\/\/www.medienkultur.at\/neu\/tag\/gesetzes-entwuerfe\/","name":"Gesetzes-Entw\u00fcrfe","slug":"gesetzes-entwuerfe","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gesetzes-Entw\u00fcrfe Archive | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/tag\/gesetzes-entwuerfe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesetzes-Entw\u00fcrfe Archive | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/tag\/gesetzes-entwuerfe\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/tag\\\/gesetzes-entwuerfe\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/tag\\\/gesetzes-entwuerfe\\\/\",\"name\":\"Gesetzes-Entw\u00fcrfe Archive | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/tag\\\/gesetzes-entwuerfe\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/tag\\\/gesetzes-entwuerfe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesetzes-Entw\u00fcrfe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesetzes-Entw\u00fcrfe Archive | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/tag\/gesetzes-entwuerfe\/","og_locale":"de_DE","og_type":"article","og_title":"Gesetzes-Entw\u00fcrfe Archive | Vereinigung f\u00fcr Medienkultur","og_url":"https:\/\/www.medienkultur.at\/neu\/tag\/gesetzes-entwuerfe\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.medienkultur.at\/neu\/tag\/gesetzes-entwuerfe\/","url":"https:\/\/www.medienkultur.at\/neu\/tag\/gesetzes-entwuerfe\/","name":"Gesetzes-Entw\u00fcrfe Archive | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/tag\/gesetzes-entwuerfe\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/tag\/gesetzes-entwuerfe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Gesetzes-Entw\u00fcrfe"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags\/2531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts?tags=2531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}