{"id":6641,"date":"2019-10-04T07:45:35","date_gmt":"2019-10-04T06:45:35","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=6641"},"modified":"2019-10-07T07:06:57","modified_gmt":"2019-10-07T06:06:57","slug":"saechsische-doerfer-an-polnischer-grenze-und-afd","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/","title":{"rendered":"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD"},"content":{"rendered":"<p>Folgenden Text fand ich in der Neuen Z\u00fcrcher online Freitag 4.Okt. 2019. Geschildert werden D\u00f6rfer an der polnischen Grenze in Ostdeutschland und situative Hintergr\u00fcnde f\u00fcr den Aufstieg der AfD (Hans H\u00f6gl) <\/p>\n<p>Hier sei mal eine Kneipe gewesen, und da habe es mal einen Laden gegeben. Herr Hoffmann, der Taxifahrer aus G\u00f6rlitz, deutet immer wieder auf Punkte links und rechts an der Strasse. Er scheint ein sicheres Gesp\u00fcr f\u00fcr die Aufl\u00f6sungserscheinungen s\u00e4chsischer D\u00f6rfer zu haben. Er weiss, welche H\u00f6fe leer stehen und welche Restaurantbesitzer die DDR-Toiletten bis heute nicht ausgewechselt haben.\u00a0<\/p>\n<p>Wir sind auf dem Weg von G\u00f6rlitz in die Gemeinde Neisseaue, eine Ansammlung versprengter Strassend\u00f6rfer an der deutsch-polnischen Grenze. Der gr\u00f6sste Ort heisst Zodel und hat etwas mehr als 500 Einwohner, der kleinste ist Emmerichswalde mit 13. Das ganze Gebiet ist mehr Naturreservat als Zivilisation, auf einem Quadratkilometer leben 36 Menschen. Der Ort wirbt damit, die \u00ab\u00f6stlichste Gemeinde Deutschlands\u00bb zu sein. Man ist also in einem Raum, der schon fast Polen, aber immer noch Deutschland ist. Bei der Europawahl w\u00e4hlten hier 46,4 Prozent der Menschen die Alternative f\u00fcr Deutschland. Es war ein Rekordwert selbst f\u00fcr Sachsen.<br \/>\nSeit der Wahl ist von einer Spaltung des Landes die Rede. Die Gr\u00fcnen nehmen die westdeutschen St\u00e4dte ein, die AfD r\u00e4umt in den ostdeutschen D\u00f6rfern ab. In Sachsen und in Brandenburg machte die AfD das beste Ergebnis aller Parteien, in Th\u00fcringen das zweitbeste. In allen drei Bundesl\u00e4ndern finden im Herbst Wahlen statt, und in G\u00f6rlitz k\u00f6nnte bereits im Juni der erste AfD-Politiker in Deutschland zum Oberb\u00fcrgermeister gew\u00e4hlt werden. Der Polizeikommissar Sebastian Wippel liegt nach dem ersten Wahlgang an der Spitze. Seine Plakate h\u00e4ngen in der ganzen Gegend: \u00abEin G\u00f6rlitzer. Mit Sicherheit!\u00bb<\/p>\n<p>\u00abWir sind am Arsch der Welt\u00bb<br \/>\nAlleen s\u00e4umen die Strassen, dahinter liegen weite Felder. Menschen ziehen weg, und die Natur arbeitet langsam, aber beharrlich daran, das Gel\u00e4nde zur\u00fcckzuerobern. Dorfstrukturen wie in Bayern habe es hier nie gegeben, sagt der Taxifahrer Hoffmann. Die Leute h\u00e4tten nicht auf dem Dorfplatz getratscht, sondern beim B\u00e4cker und \u00fcber die Z\u00e4une hinweg. Wir sind gerade auf der Suche nach dem \u00f6stlichsten Punkt Deutschlands zwischen Deschka und Zentendorf, da soll eine Art Denkmal stehen. Aber der Taxifahrer Hoffmann verf\u00e4hrt sich schon zum wiederholten Mal. Er chauffiert haupts\u00e4chlich kranke Menschen in der Gegend herum, zu Denkm\u00e4lern f\u00e4hrt er nur selten. Schliesslich h\u00e4lt er vor einem Haus und bittet einen alten Deschkaer einzusteigen, um den Weg zu zeigen.<\/p>\n<p>\u00abKneipen gibt es keine mehr, Bus weiss ich nicht, wir sind am Arsch der Welt\u00bb, so fasst der neue Passagier die allgemeine Lage zusammen. Auch einen Laden gebe es in Deschka schon lange nicht mehr, Anfang der neunziger Jahre habe der \u00abKonsum\u00bb geschlossen. Einmal in der Woche kommen nun Verkaufswagen vorbei und bringen Brot, Fleisch und Gem\u00fcse. Ein Sparkassenbus versorgt die Leute mit Bargeld. Wie h\u00e4lt der Mann es mit der AfD? \u00abMuss nicht sein.\u00bb Er sei aber ohnehin nicht zur Wahl gegangen, denn das Wahllokal sei in Zodel gewesen, drei Kilometer entfernt. Fr\u00fcher sei er manchmal zum \u00f6stlichsten Punkt Deutschlands spaziert, aber seit der Hund gestorben sei, mache er das nicht mehr. Alles scheint bei dem Mann aufs Aufh\u00f6ren angelegt zu sein.<\/p>\n<p>Nur ans Wegziehen denkt er offenbar nicht. Er sei hier aufgewachsen, habe ein Haus gebaut und 44 Jahre lang als Polizist gearbeitet. Jetzt versuche er, so lange es gehe, hierzubleiben. Auch wenn das nicht immer sch\u00f6n sei. Manchmal funktioniere nicht einmal das Festnetz, sagt der alte Polizist. Dieses Jahr h\u00e4tten Kriminelle schon zweimal Telefonleitungen abgebaut, Hunderte von Metern, nur wegen des Kupfers.\u00a0<br \/>\nViel scheint der Mann nicht mehr zu erwarten. Wenn aber jemand k\u00e4me und ein paar Dinge in Ordnung br\u00e4chte, h\u00e4tte er wohl nichts dagegen. Den AfD-Polizisten, der in G\u00f6rlitz Oberb\u00fcrgermeister werden will, findet er zum Beispiel sympathisch. Das heisst, er sei zumindest \u00abkein Hirnverbrannter\u00bb.<\/p>\n<p>Der \u00f6stlichste Zipfel Deutschlands ist ein seltsames Arrangement. Dazu geh\u00f6ren ein grosser Stein, ein \u00abZipfel-Buch\u00bb, in das sich die G\u00e4ste eintragen k\u00f6nnen, ein H\u00e4uschen, das wie der Einstieg zu einem Atombunker aussieht, und eine verblichene Deutschlandfahne. Es w\u00e4re eine L\u00fcge, zu behaupten, dass die Reisegruppe an diesem Punkt besonders ber\u00fchrt sei. Der Taxifahrer Hoffmann nutzt den Halt f\u00fcr eine Rauchpause. Ein bisschen scheint er sich auch Sorgen zu machen um seinen Wagen, denn die Fahrt zum \u00f6stlichsten Punkt Deutschlands gleicht einer Safari.<\/p>\n<p>Am Ende der Reise stehen die AfD-Politiker Roberto Kuhnert und Heiko Titze an der Dorfstrasse in Zodel. Kuhnert ist selbst\u00e4ndiger Baudienstleister und f\u00fchrt die AfD-Regionalgruppe Weisswasser, zu der auch Neisseaue geh\u00f6rt. Titze ist Polizeibeamter im Ruhestand und kommt aus H\u00e4hnichen, ein paar Kilometer weiter n\u00f6rdlich von hier. M\u00e4nner wie Kuhnert und Titze ziehen nun f\u00fcr die AfD in die deutschen Parlamente ein, beide wurden vor einer Woche in den G\u00f6rlitzer Kreistag gew\u00e4hlt. Das Gespr\u00e4ch findet in der Landb\u00e4ckerei in Zodel statt, aber ganz wohl ist es den beiden Herren dabei nicht. Kuhnert redet betont leise, doch es n\u00fctzt nichts. \u00abDa wird es mir ganz \u00fcbel, wenn ich das h\u00f6re!\u00bb, f\u00e4hrt ihn eine Kundin nach wenigen Minuten an. Kuhnert hat gerade berichtet, wie sehr die CDU in Sachsen versagt habe. Wenig sp\u00e4ter mischt sich eine weitere Frau ein: \u00abMinisterpr\u00e4sident Kretschmer hat viel bewirkt in der Region!\u00bb<br \/>\n54 Prozent w\u00e4hlen in Neisseaue nicht die AfD, daran haben die beiden Damen noch einmal erinnert. Kuhnert diskutiert mit ihnen, bis der B\u00e4cker einschreitet: \u00abHier muss bedient werden!\u00bb Er h\u00e4tte auch sagen k\u00f6nnen: \u00abHier darf nicht politisiert werden!\u00bb Der B\u00e4cker f\u00fcrchtet offenbar um sein Gesch\u00e4ft. In einem Dorf mit 500 Einwohnern kann er es sich nicht leisten, dass AfD-Politiker im Laden die CDU-Kundschaft vertreiben. Solche Szenen wie eben seien eine Ausnahme, sagt Kuhnert sp\u00e4ter. \u00abAber manche verteidigen die CDU heute so, wie fr\u00fcher Unverbesserliche die SED verteidigt haben, als es mit der DDR zu Ende ging.\u00bb Es sei Zeit f\u00fcr eine \u00abneue Wende\u00bb, sagt Kuhnert.<\/p>\n<p>\u00abDie Region f\u00fchlt sich abgeh\u00e4ngt\u00bb<br \/>\nTitze ist ein schweigsamer Mann, meistens hat er die Arme verschr\u00e4nkt und die Mundecken leicht nach unten gezogen. Eigentlich w\u00e4re er noch immer gern Polizist, wie er sagt. Aber er habe einen Dienstunfall gehabt und danach sieben Operationen. Manchmal setzt er an und will etwas sagen, aber Kuhnert ist schneller. Der AfD-Mann aus Weisswasser gibt gern den Welterkl\u00e4rer. Vor allem aber ist er begeistert von den j\u00fcngsten Wahlerfolgen. \u00abUns w\u00e4hlt der komplette Querschnitt der Gesellschaft\u00bb, sagt er. Wie zum Beweis f\u00fcgt Titze hinzu, \u00abmein Hausarzt hat mich auch gew\u00e4hlt\u00bb. Kuhnert: \u00abEs gibt keine Alternative zur Alternative!\u00bb Aber warum w\u00e4hlen gerade in Neisseaue so viele Leute die AfD? \u00abDie Region f\u00fchlt sich abgeh\u00e4ngt\u00bb, sagt Kuhnert. \u00abDas ist nicht nur ein Gef\u00fchl, es ist so. Die Industrie siedelt sich mittlerweile in Polen an.\u00bb<br \/>\nDas eigene Ungl\u00fcck scheint sich im Erfolg der Polen noch zu vergr\u00f6ssern. Titze sagt: \u00abDie Wirtschaft fehlt, die Jugend zieht weg. Viele Handwerker wollen junge Leute gar nicht mehr ausbilden, weil diese ohnehin in den Westen auswandern.\u00bb F\u00fcr Kuhnert ist das Konzentrat aller Probleme die geringe Kaufkraft. Titze kann das nur best\u00e4tigen: \u00abDie Leute k\u00f6nnen sich ja ein Bier im Gasthaus kaum noch leisten.\u00bb Der pure Patriotismus ende beim Portemonnaie, erkl\u00e4rt Kuhnert. F\u00fcr den Friseur, Zigaretten und zum Tanken fahren viele Deutsche, die im Grenzgebiet leben, nach Polen.<\/p>\n<p>\u00abMan will keine Zust\u00e4nde wie in Berlin\u00bb<br \/>\nEine tragende Rolle f\u00fcr den Erfolg der AfD spiele auch die Fl\u00fcchtlingskrise, sagt Kuhnert. \u00abMan will hier keine Zust\u00e4nde wie in Berlin.\u00bb Aber eigentlich geht es nicht einmal um Berlin, es geht schon um G\u00f6rlitz und Zwickau. So peripher die Menschen auch leben, viele haben Angst, dass sie ihre Heimat irgendwann nicht mehr erkennen k\u00f6nnten. Titze erz\u00e4hlt, wie er k\u00fcrzlich durch die Stadt spaziert sei, in der er geboren wurde. In der Einkaufsstrasse von Zwickau sehe es heute aus wie auf einem t\u00fcrkischen Basar. Titze wirkt weniger emp\u00f6rt als entt\u00e4uscht.<br \/>\nDer B\u00e4cker h\u00f6rt den Neopolitikern mit grimmiger Miene zu. Aber nur wenn keine Kunden im Laden sind. Irgendwann fragt er die AfD-M\u00e4nner: \u00abDenken Sie tats\u00e4chlich, dass die Presse Ihnen hilft?\u00bb Er r\u00e4t ihnen, besser zu schweigen, denn Journalisten w\u00fcrden nur Unsinn verbreiten. \u00abJetzt haben wir dieselbe Situation wie am 17.\u00a0Juni 1953\u00bb, sagt er. \u00abJournalisten kommen zu uns, um Sensationsberichte zu schreiben. Vorher hat sich f\u00fcr den Osten niemand interessiert!\u00bb Kuhnert beschwichtigt den B\u00e4cker und macht seine heiser-feine Stimme noch etwas feiner. Der Vergleich der jetzigen politischen Situation mit dem Volksaufstand von 1953 in Berlin scheint niemanden zu wundern. Es sind die Relationen, in denen man hier denkt. Der Kampf gegen die SED wird bald mit dem Kampf gegen die CDU verglichen, der Volksaufstand von 1953 mit der Europawahl von 2019, die politischen Umbr\u00fcche der heutigen Zeit mit der Wende von 1989.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Folgenden Text fand ich in der Neuen Z\u00fcrcher online Freitag 4.Okt. 2019. Geschildert werden D\u00f6rfer an der polnischen Grenze in Ostdeutschland und situative Hintergr\u00fcnde f\u00fcr den Aufstieg der AfD (Hans H\u00f6gl) Hier sei mal eine Kneipe gewesen, und da habe es mal einen Laden gegeben. Herr Hoffmann, der Taxifahrer aus G\u00f6rlitz, deutet immer wieder auf &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/\" class=\"more-link\"><span class=\"screen-reader-text\">S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,23],"tags":[5067,5064,5069,3847,5062,5065,5066,5063,1011,5061,5068],"class_list":["post-6641","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-medienschmankerl","tag-abwanderung","tag-afd-politiker","tag-am-arsch-der-welt","tag-auslaenderfrage","tag-benachteiligung","tag-cdu","tag-doerfer-in-neuen-bundeslaendern","tag-goerlitz","tag-hans-hoegl","tag-ostdeutsche","tag-region-abgehaengt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"Folgenden Text fand ich in der Neuen Z\u00fcrcher online Freitag 4.Okt. 2019. Geschildert werden D\u00f6rfer an der polnischen Grenze in Ostdeutschland und situative Hintergr\u00fcnde f\u00fcr den Aufstieg der AfD (Hans H\u00f6gl) Hier sei mal eine Kneipe gewesen, und da habe es mal einen Laden gegeben. Herr Hoffmann, der Taxifahrer aus G\u00f6rlitz, deutet immer wieder auf &hellip; S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-04T06:45:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-07T06:06:57+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/saechsische-doerfer-an-polnischer-grenze-und-afd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/saechsische-doerfer-an-polnischer-grenze-und-afd\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD\",\"datePublished\":\"2019-10-04T06:45:35+00:00\",\"dateModified\":\"2019-10-07T06:06:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/saechsische-doerfer-an-polnischer-grenze-und-afd\\\/\"},\"wordCount\":1542,\"commentCount\":0,\"keywords\":[\"Abwanderung\",\"Afd Politiker\",\"Am Arsch der Welt\",\"Ausl\u00e4nderfrage\",\"Benachteiligung?\",\"CDU\",\"D\u00f6rfer in neuen Bundesl\u00e4ndern\",\"G\u00f6rlitz\",\"Hans H\u00f6gl\",\"Ostdeutsche\",\"Region abgeh\u00e4ngt\"],\"articleSection\":[\"J\u00dcNGSTE BEITR\u00c4GE\",\"Medienschmankerl\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/saechsische-doerfer-an-polnischer-grenze-und-afd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/saechsische-doerfer-an-polnischer-grenze-und-afd\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/saechsische-doerfer-an-polnischer-grenze-und-afd\\\/\",\"name\":\"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2019-10-04T06:45:35+00:00\",\"dateModified\":\"2019-10-07T06:06:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/saechsische-doerfer-an-polnischer-grenze-und-afd\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/saechsische-doerfer-an-polnischer-grenze-und-afd\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/saechsische-doerfer-an-polnischer-grenze-und-afd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/","og_locale":"de_DE","og_type":"article","og_title":"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD | Vereinigung f\u00fcr Medienkultur","og_description":"Folgenden Text fand ich in der Neuen Z\u00fcrcher online Freitag 4.Okt. 2019. Geschildert werden D\u00f6rfer an der polnischen Grenze in Ostdeutschland und situative Hintergr\u00fcnde f\u00fcr den Aufstieg der AfD (Hans H\u00f6gl) Hier sei mal eine Kneipe gewesen, und da habe es mal einen Laden gegeben. Herr Hoffmann, der Taxifahrer aus G\u00f6rlitz, deutet immer wieder auf &hellip; S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2019-10-04T06:45:35+00:00","article_modified_time":"2019-10-07T06:06:57+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD","datePublished":"2019-10-04T06:45:35+00:00","dateModified":"2019-10-07T06:06:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/"},"wordCount":1542,"commentCount":0,"keywords":["Abwanderung","Afd Politiker","Am Arsch der Welt","Ausl\u00e4nderfrage","Benachteiligung?","CDU","D\u00f6rfer in neuen Bundesl\u00e4ndern","G\u00f6rlitz","Hans H\u00f6gl","Ostdeutsche","Region abgeh\u00e4ngt"],"articleSection":["J\u00dcNGSTE BEITR\u00c4GE","Medienschmankerl"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/","url":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/","name":"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2019-10-04T06:45:35+00:00","dateModified":"2019-10-07T06:06:57+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/saechsische-doerfer-an-polnischer-grenze-und-afd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"S\u00e4chsische D\u00f6rfer an polnischer Grenze und AfD"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/6641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=6641"}],"version-history":[{"count":1,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/6641\/revisions"}],"predecessor-version":[{"id":6642,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/6641\/revisions\/6642"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=6641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=6641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=6641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}