{"id":5810,"date":"2019-04-24T21:40:46","date_gmt":"2019-04-24T20:40:46","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=5810"},"modified":"2019-04-25T07:15:23","modified_gmt":"2019-04-25T06:15:23","slug":"nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/","title":{"rendered":"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus"},"content":{"rendered":"<p> HANS H\u00d6GL<\/p>\n<p>In der Internetversion der Wiener Zeitung &#8222;Die Presse&#8220; fand ich Fotos gro\u00dfer Qualit\u00e4t \u00fcber Korea. Darin \u00e4hnelt die &#8222;Presse&#8220; dem spanischen Blatt &#8222;El Pais&#8220;.Qualitative Fotos sind oft sehr aussageintensiv und darum von Interesse f\u00fcr die &#8222;Medienkultur&#8220;. Im \u00dcbrigen: Auch Zeitschriften wie der &#8222;Stern&#8220; und &#8222;Geo&#8220; oder &#8222;National Geographic&#8220; haben Fotos von hoher Qualit\u00e4t.<\/p>\n<p>Die Presse: Es ist nicht bekannt, wie viel Geld Nordkoreas F\u00fchrer Kim Jung-Un wirklich dazu nutzt, die Koreanische Volksarmee zu finanzieren. Allerdings sagt man, dass es ein betr\u00e4chtliches Verm\u00f6gen sein muss. Die Nordkoreanische Armee nutzt Laser und Fernlenkgeschosse, die in anderen L\u00e4ndern verboten sind, und hat au\u00dferdem eine eindrucksvolle Einheit f\u00fcr Cyber-Kriegsf\u00fchrung. Es ist f\u00fcr jeden Nordkoreaner \u00fcber 18 Jahren verpflichtend, sich einzuschreiben, sogar f\u00fcr Frauen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HANS H\u00d6GL In der Internetversion der Wiener Zeitung &#8222;Die Presse&#8220; fand ich Fotos gro\u00dfer Qualit\u00e4t \u00fcber Korea. Darin \u00e4hnelt die &#8222;Presse&#8220; dem spanischen Blatt &#8222;El Pais&#8220;.Qualitative Fotos sind oft sehr aussageintensiv und darum von Interesse f\u00fcr die &#8222;Medienkultur&#8220;. Im \u00dcbrigen: Auch Zeitschriften wie der &#8222;Stern&#8220; und &#8222;Geo&#8220; oder &#8222;National Geographic&#8220; haben Fotos von hoher Qualit\u00e4t. &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/\" class=\"more-link\"><span class=\"screen-reader-text\">Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[4167,421,4170,4169,4166,4168,4165],"class_list":["post-5810","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-der-stern","tag-die-presse","tag-fotos-hoher-qualitaet","tag-geo","tag-militaerruestung","tag-national-geographic","tag-nordkorea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"HANS H\u00d6GL In der Internetversion der Wiener Zeitung &#8222;Die Presse&#8220; fand ich Fotos gro\u00dfer Qualit\u00e4t \u00fcber Korea. Darin \u00e4hnelt die &#8222;Presse&#8220; dem spanischen Blatt &#8222;El Pais&#8220;.Qualitative Fotos sind oft sehr aussageintensiv und darum von Interesse f\u00fcr die &#8222;Medienkultur&#8220;. Im \u00dcbrigen: Auch Zeitschriften wie der &#8222;Stern&#8220; und &#8222;Geo&#8220; oder &#8222;National Geographic&#8220; haben Fotos von hoher Qualit\u00e4t. &hellip; Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-24T20:40:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-25T06:15:23+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus\",\"datePublished\":\"2019-04-24T20:40:46+00:00\",\"dateModified\":\"2019-04-25T06:15:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\\\/\"},\"wordCount\":146,\"commentCount\":0,\"keywords\":[\"\\\"Der Stern\\\"\",\"Die Presse\",\"Fotos hoher Qualit\u00e4t\",\"Geo\",\"Milit\u00e4rr\u00fcstung\",\"National Geographic\",\"Nordkorea\"],\"articleSection\":[\"J\u00dcNGSTE BEITR\u00c4GE\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\\\/\",\"name\":\"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2019-04-24T20:40:46+00:00\",\"dateModified\":\"2019-04-25T06:15:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/","og_locale":"de_DE","og_type":"article","og_title":"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus | Vereinigung f\u00fcr Medienkultur","og_description":"HANS H\u00d6GL In der Internetversion der Wiener Zeitung &#8222;Die Presse&#8220; fand ich Fotos gro\u00dfer Qualit\u00e4t \u00fcber Korea. Darin \u00e4hnelt die &#8222;Presse&#8220; dem spanischen Blatt &#8222;El Pais&#8220;.Qualitative Fotos sind oft sehr aussageintensiv und darum von Interesse f\u00fcr die &#8222;Medienkultur&#8220;. Im \u00dcbrigen: Auch Zeitschriften wie der &#8222;Stern&#8220; und &#8222;Geo&#8220; oder &#8222;National Geographic&#8220; haben Fotos von hoher Qualit\u00e4t. &hellip; Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2019-04-24T20:40:46+00:00","article_modified_time":"2019-04-25T06:15:23+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus","datePublished":"2019-04-24T20:40:46+00:00","dateModified":"2019-04-25T06:15:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/"},"wordCount":146,"commentCount":0,"keywords":["\"Der Stern\"","Die Presse","Fotos hoher Qualit\u00e4t","Geo","Milit\u00e4rr\u00fcstung","National Geographic","Nordkorea"],"articleSection":["J\u00dcNGSTE BEITR\u00c4GE"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/","url":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/","name":"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2019-04-24T20:40:46+00:00","dateModified":"2019-04-25T06:15:23+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/nordkorea-gibt-ein-vermoegen-fuer-seine-streitkraefte-aus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Nordkorea gibt ein Verm\u00f6gen f\u00fcr seine Streitkr\u00e4fte aus"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/5810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=5810"}],"version-history":[{"count":5,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/5810\/revisions"}],"predecessor-version":[{"id":5816,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/5810\/revisions\/5816"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=5810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=5810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=5810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}