{"id":5618,"date":"2019-03-21T09:35:23","date_gmt":"2019-03-21T08:35:23","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=5618"},"modified":"2019-03-22T22:53:33","modified_gmt":"2019-03-22T21:53:33","slug":"digitalisierung-grosse-chance-fuer-volkswirtschaft","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/","title":{"rendered":"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft"},"content":{"rendered":"<p>Jakob Herburger. Di\u00f6zesaner Pressereferent. St. P\u00f6lten<br \/>\n(Beitrag ausgew\u00e4hlt von Hans H\u00f6gl) <\/p>\n<p>Symposion: Mensch und Digitalisierung 15.-16.3.2019 <\/p>\n<p>Referent Dr. Hans Zeger, Mathematiker, Philosoph und Obmann der ARGE Daten sowie Inhaber einer Firma mit 15 Mitarbeitern sprach \u00fcber \u201eTargeting, Taching, Nudging \u2013 Schafft Europa den Anschluss an die Informationsgesellschaft?\u201c&#8230;. <\/p>\n<p>Er verglich die in \u00d6sterreich weit verbreitete \u201eDigitalisierungsskepsis\u201c mit der Einf\u00fchrung der Telefonkommunikation in den Vereinigten Staaten: \u201eIn Amerika wurde mit der Einf\u00fchrung des Telefons bef\u00fcrchtet, dass volkswirtschaftlich gesehen, viel zu viele Leute Telefonvermittler sein m\u00fcssten. Diesem Problem wurde durch die Erfindung des Selbstw\u00e4hlverfahrens Einhalt geboten.\u201c In \u00d6sterreich seien die letzten Telefonvermittlungs\u00e4mter typischerweise erst 1972 aufgel\u00f6st worden, was unn\u00f6tige Kosten verursacht h\u00e4tte. Auch die Erfindung des Staubsaugers habe den Arbeitsverlust von Millionen Dienstnehmern im Reinigungsbereich bedeutet. Durch die Dampfmaschine h\u00e4tten sich Millionen Arbeitskr\u00e4fte umorientieren m\u00fcssen. \u201eWer das ablehnt soll sich \u00fcberlegen, ob er tats\u00e4chlich die menschenunw\u00fcrdigen Arbeitsbedingungen der Vergangenheit wieder haben m\u00f6chte.\u201c, so der Obmann der ARGE Daten.<\/p>\n<p>Unglaubliche Dynamik der Automatisierung<\/p>\n<p>Verglichen mit anderen Industrienationen h\u00e4tten \u201edie \u00d6sterreicher sich durch ein System von Kammern und Verwaltungswesen ein \u00fcberbordendes System geschaffen, in dem nicht vorrangig Qualifikation, sondern Verankerung im System z\u00e4hlt. Das ist verglichen mit dem Weltniveau vorgestrig.\u201c Auch deshalb h\u00e4tte \u00d6sterreich eine horrende Abgabenquote, die bei 70 Prozent liege. 70 Prozent der Lohnkosten eines Arbeitgebers seien Abgaben, nur die restlichen 30 Prozent seien der Nettolohn.<\/p>\n<p>Es sei den Menschen hierzulande viel zu wenig bewusst, dass bis zu 1,4 Millionen Arbeitsstellen in \u00d6sterreich mittelfristig durch Automatisierung ersetzt werden k\u00f6nnten. \u201eWir haben derzeit aber keine anderen Jobs f\u00fcr diese Leute. Globale Banken wie N26 haben ein paar hundert Mitarbeiter und betreuen damit dutzende Millionen Kunden. Die zehntausenden Angestellten im Raiffeisen-Bankensektor oder im Erste-Bank-Sektor gibt es haupts\u00e4chlich nur noch aus sentimentalen Gr\u00fcnden.\u201c Es brauche Mut zur Digitalisierung. Wir in \u00d6sterreich sollten endlich beherzter mitmachen, so Dr. Hans G. Zeger.<\/p>\n<p>Auf die Frage, was passiere, wenn Europa die Digitalisierung nicht zeitgerecht schaffe, antwortete Dr. Hans Zeger: \u201eEs gibt bereits 400 Millionen Mittelstandschinesen, 300 Millionen Mittelstandsinder, 30 Millionen Mittelstandsrussen und 20 Millionen Mittelstandsaraber. Fast alle wollen nach Europa, um die Sehensw\u00fcrdigkeiten und Kulturg\u00fcter zu besichtigen. Falls wir die Digitalisierung nicht ad\u00e4quat schaffen, k\u00f6nnte eine unserer M\u00f6glichkeiten sein, unser Freilichtmuseum touristisch auszuschlachten.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jakob Herburger. Di\u00f6zesaner Pressereferent. St. P\u00f6lten (Beitrag ausgew\u00e4hlt von Hans H\u00f6gl) Symposion: Mensch und Digitalisierung 15.-16.3.2019 Referent Dr. Hans Zeger, Mathematiker, Philosoph und Obmann der ARGE Daten sowie Inhaber einer Firma mit 15 Mitarbeitern sprach \u00fcber \u201eTargeting, Taching, Nudging \u2013 Schafft Europa den Anschluss an die Informationsgesellschaft?\u201c&#8230;. Er verglich die in \u00d6sterreich weit verbreitete \u201eDigitalisierungsskepsis\u201c &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/\" class=\"more-link\"><span class=\"screen-reader-text\">Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3989,3993,3984,3994,3988,3985,3992,3987,3990,3986,3991],"class_list":["post-5618","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-arbeitsplaetzeverlust","tag-arbeitswelt-umorientierung","tag-digitalisierung-chance","tag-europa-als-freilichtmuseum","tag-folgen-der-automatisierung","tag-hans-zeger-arge-daten","tag-kammerwesen-in-oesterreich","tag-mut-zur-digitalisierung","tag-oesterreich-hinkt-nach","tag-schafft-europa-den-anschluss","tag-steuerquote-sehr-hoch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"Jakob Herburger. Di\u00f6zesaner Pressereferent. St. P\u00f6lten (Beitrag ausgew\u00e4hlt von Hans H\u00f6gl) Symposion: Mensch und Digitalisierung 15.-16.3.2019 Referent Dr. Hans Zeger, Mathematiker, Philosoph und Obmann der ARGE Daten sowie Inhaber einer Firma mit 15 Mitarbeitern sprach \u00fcber \u201eTargeting, Taching, Nudging \u2013 Schafft Europa den Anschluss an die Informationsgesellschaft?\u201c&#8230;. Er verglich die in \u00d6sterreich weit verbreitete \u201eDigitalisierungsskepsis\u201c &hellip; Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-21T08:35:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-22T21:53:33+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/digitalisierung-grosse-chance-fuer-volkswirtschaft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/digitalisierung-grosse-chance-fuer-volkswirtschaft\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft\",\"datePublished\":\"2019-03-21T08:35:23+00:00\",\"dateModified\":\"2019-03-22T21:53:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/digitalisierung-grosse-chance-fuer-volkswirtschaft\\\/\"},\"wordCount\":391,\"commentCount\":0,\"keywords\":[\"Arbeitspl\u00e4tzeverlust\",\"Arbeitswelt-Umorientierung\",\"Digitalisierung Chance\",\"Europa als Freilichtmuseum\",\"Folgen der Automatisierung\",\"Hans Zeger ARGE Daten\",\"Kammerwesen in \u00d6sterreich\",\"Mut zur Digitalisierung\",\"\u00d6sterreich hinkt nach\",\"Schafft Europa den Anschluss?\",\"Steuerquote sehr hoch\"],\"articleSection\":[\"J\u00dcNGSTE BEITR\u00c4GE\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/digitalisierung-grosse-chance-fuer-volkswirtschaft\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/digitalisierung-grosse-chance-fuer-volkswirtschaft\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/digitalisierung-grosse-chance-fuer-volkswirtschaft\\\/\",\"name\":\"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2019-03-21T08:35:23+00:00\",\"dateModified\":\"2019-03-22T21:53:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/digitalisierung-grosse-chance-fuer-volkswirtschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/digitalisierung-grosse-chance-fuer-volkswirtschaft\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/digitalisierung-grosse-chance-fuer-volkswirtschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft | Vereinigung f\u00fcr Medienkultur","og_description":"Jakob Herburger. Di\u00f6zesaner Pressereferent. St. P\u00f6lten (Beitrag ausgew\u00e4hlt von Hans H\u00f6gl) Symposion: Mensch und Digitalisierung 15.-16.3.2019 Referent Dr. Hans Zeger, Mathematiker, Philosoph und Obmann der ARGE Daten sowie Inhaber einer Firma mit 15 Mitarbeitern sprach \u00fcber \u201eTargeting, Taching, Nudging \u2013 Schafft Europa den Anschluss an die Informationsgesellschaft?\u201c&#8230;. Er verglich die in \u00d6sterreich weit verbreitete \u201eDigitalisierungsskepsis\u201c &hellip; Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2019-03-21T08:35:23+00:00","article_modified_time":"2019-03-22T21:53:33+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft","datePublished":"2019-03-21T08:35:23+00:00","dateModified":"2019-03-22T21:53:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/"},"wordCount":391,"commentCount":0,"keywords":["Arbeitspl\u00e4tzeverlust","Arbeitswelt-Umorientierung","Digitalisierung Chance","Europa als Freilichtmuseum","Folgen der Automatisierung","Hans Zeger ARGE Daten","Kammerwesen in \u00d6sterreich","Mut zur Digitalisierung","\u00d6sterreich hinkt nach","Schafft Europa den Anschluss?","Steuerquote sehr hoch"],"articleSection":["J\u00dcNGSTE BEITR\u00c4GE"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/","url":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/","name":"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2019-03-21T08:35:23+00:00","dateModified":"2019-03-22T21:53:33+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/digitalisierung-grosse-chance-fuer-volkswirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Digitalisierung: Gro\u00dfe Chance f\u00fcr Volkswirtschaft"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/5618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=5618"}],"version-history":[{"count":3,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/5618\/revisions"}],"predecessor-version":[{"id":5632,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/5618\/revisions\/5632"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=5618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=5618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=5618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}