{"id":3709,"date":"2017-04-25T09:33:42","date_gmt":"2017-04-25T07:33:42","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=3709"},"modified":"2017-04-29T12:01:37","modified_gmt":"2017-04-29T10:01:37","slug":"armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/","title":{"rendered":"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung"},"content":{"rendered":"<p>Gastbeitrag: S\u00fcddeutsche Zeitung\u00a0 24. April 2017, 18:58 Uhr<\/p>\n<h2><strong>\u00a0ORF-Wolf<\/strong> zu kritisch, zu hartn\u00e4ckig<\/h2>\n<section class=\"topenrichment\">\n<figure class=\"asset-image asset-image--image_big\">\n<div class=\"asset-image__image-wrapper\" data-bind=\"{&quot;zoomimage&quot;:{&quot;url&quot;: &quot;http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/860x860?v=1493044623000&amp;method=resize&quot;, &quot;width&quot;: &quot;860&quot;, &quot;height&quot;: &quot;auto&quot;}}\"><a class=\"asset-image__link\" href=\"http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/860x860?v=1493044623000&amp;method=resize\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\"asset-image__image-tag\" src=\"http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/940x528?v=1493044623000\" sizes=\"(min-width: 940px) 640px,100vw\" srcset=\"http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/156x88?v=1493044623000 156w, http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/263x148?v=1493044623000 263w, http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/460x259?v=1493044623000 460w, http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/560x315?v=1493044623000 560w, http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/680x382?v=1493044623000 680w, http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/940x528?v=1493044623000 940w\" alt=\"Sommergespr\u00e4che\" \/><i><\/i> <\/a><\/div><figcaption class=\"asset-image__description\">F\u00fcr die &#8222;ORF-Sommergespr\u00e4che&#8220; besuchte Armin Wolf 2016 jeweils montags Parteivorsitzende dort, wo sie aufgewachsen sind.<\/figcaption><\/figure>\n<\/section>\n<section id=\"article-body\" class=\"body\">\n<div class=\"ad\" data-adtile=\"8\">\n<div id=\"iqadtile8\" class=\"iqad\" data-bind=\"{&quot;widget.LiquidAds&quot;: {}}\" data-creative-asset=\"iqadtile8\" data-google-query-id=\"CJCjnpWGv9MCFUwh0wodpAUEvA\">\n<div id=\"google_ads_iframe_\/183\/iqdsde\/medien\/artikel_4__container__\">Was anderswo als gute journalistische Arbeit gilt, bringt ORF-Moderator Armin Wolf bei seinem Sender in Schwierigkeiten.<\/div>\n<\/div>\n<\/div>\n<section class=\"authors resized\">\n<div class=\"authorContainer\">\n<div class=\"authorProfileContainer\"><\/div>\n<div class=\"authorProfileContainer\"><span class=\"moreInfo\"><strong>Von <span id=\"abbr-ck\" data-abbr=\"ck\">Cathrin Kahlweit<\/span><\/strong> <\/span><\/div>\n<div id=\"popup-ck\" class=\"containerBox closeable\">\n<div class=\"authorPopup authorPopup-ck\">\n<div class=\"metadata\">\u00a0Gerade erst hat sich der \u00d6sterreichische Rundfunk (<a class=\"themelink\" href=\"http:\/\/www.sueddeutsche.de\/thema\/ORF\" data-pagetype=\"THEME\">ORF<\/a>) selbst gefeiert, nun fliegen schon wieder die Fetzen. Bei der <span class=\"nowrap\">28<\/span>. Verleihung des \u00f6sterreichischen Film-und Fernsehpreises &#8222;Romy&#8220; haben am Wochenende die \u00fcblichen Verd\u00e4chtigen ihre Preise abgeholt: Tobias Moretti als beliebtester Schauspieler zum achten, Ursula Strauss zum vierten Mal&#8230;&#8230;<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p>Beim ORF war man erfreut \u00fcber die Preisflut, aber geredet wird \u00fcber anderes. Das Magazin <i>Pro<\/i><i>fil<\/i> hat n\u00e4mlich ein Interview mit dem ORF-Onlinechef und stellvertretenden Direktor f\u00fcr Technik und neue Medien, Thomas Prantner, ver\u00f6ffentlicht, in dem er gegen den prominenten ORF-Moderator Armin Wolf ledert. Nun ist es einerseits ungew\u00f6hnlich, dass ein Manager den Ruf eines Kollegen und damit auch den des eigenen Hauses besch\u00e4digt. Andererseits kam die Aktion nicht wirklich \u00fcberraschend. So will Generaldirektor Alexander Wrabetz einen Aufr\u00e4umer zum Wellenchef f\u00fcr ORF 2 k\u00fcren, der sich ebenfalls schon sehr kritisch \u00fcber die Arbeit von Wolf ge\u00e4u\u00dfert hat. Dieser ist als popul\u00e4rer Moderator der Nachrichtensendung ZIB 2 ein Aush\u00e4ngeschild f\u00fcr den Sender &#8211; aber bei den Parteien, die im ORF entscheidenden Einfluss haben, nachhaltig unbeliebt. Er fragt ihnen zu kritisch &#8211; und zu\u00a0hartn\u00e4ckig.<\/p>\n<h3>&#8222;TV-Studio wie ein Verh\u00f6rraum oder eine Anklagebank&#8220;<\/h3>\n<p>Wenn man in Parteienzentralen und in den ORF hineinhorcht, h\u00f6rt man unz\u00e4hlige Geschichten von emp\u00f6rten Politikern aller Parteien, die sich beim Sender beschweren, weil sie sich nicht positiv genug darstellen k\u00f6nnen. Man k\u00f6nnte nun (zu Recht) meinen, das sei ein Indiz f\u00fcr gute journalistische Arbeit. Aber der designierte Wellenchef, SP\u00d6-Mann Roland Brunhofer, vergleicht diese straff gef\u00fchrten Interviews, die im Unterricht an Journalistenschulen als vorbildliche Beispiele gezeigt werden, gern schon mal mit\u00a0&#8222;Hinrichtungen&#8220;.<\/p>\n<div class=\"ad\">\n<div id=\"iqd_medrecAd\">\n<div id=\"iqd_bottomAd\">\n<p><!-- BEGIN ad tag (iqadtile4) -->Seither geht die Rede, dass Wolf entmachtet werden soll, damit er den Politikern in \u00d6sterreich mit seinen Fragen nicht mehr so l\u00e4stig fallen kann. ORF-Manager Prantner, der auf einem FP\u00d6-Ticket zu seinem Posten kam, hat nun nachgelegt und gesagt, es sei &#8222;unzumutbar f\u00fcr einen \u00f6ffentlich-rechtlichen Rundfunk, wenn das TV-Studio wie ein Verh\u00f6rraum oder eine Anklagebank wirkt&#8220;. Im <i>Kurier<\/i> ist zu lesen, dem Vernehmen nach sei dieses Interview mit Wrabetz abgestimmt\u00a0gewesen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<figure class=\"teaserable-layout teaserable-layout--teaser resized\"><figcaption class=\"teaserable-layout__figcaption\">\n<h3 class=\"teaserable-layout__title\"><strong>Angst vor den Kanalreinigern<\/strong><\/h3>\n<p><a class=\"teaserable-layout__link\" href=\"http:\/\/www.sueddeutsche.de\/medien\/rundfunk-in-oesterreich-angst-vor-den-kanalreinigern-1.3431719\"><span class=\"teaserable-layout__abstract\"> Im ORF sollen k\u00fcnftig dem Generaldirektor unterstellte Manager bei der TV-Information mitbestimmen. Die Redaktion f\u00fcrchtet Kompetenzwirrwarr und politischen Druck auf die angesehene &#8222;ZIB 2&#8220;. <\/span> <span class=\"teaserable-layout__authors\">Von Cathrin Kahlweit<\/span> <span class=\"teaserable-layout__more\">mehr &#8230;<\/span> <\/a><\/p>\n<\/figcaption><\/figure>\n<p>Prantner nennt Wolf zwar nicht beim Namen, kritisiert aber auch die Social-Media-Aktivit\u00e4ten &#8222;prominenter ORF-Autoren&#8220;, die &#8222;oft mehr der Eigenprofilierung und der Marktwertsteigerung als dem Unternehmensinteresse&#8220; dienten. Moderator Wolf hat auch dort viel Einfluss, der nicht immer gesch\u00e4tzt wird: <span class=\"nowrap\">250 000<\/span> Likes auf Facebook und gut <span class=\"nowrap\">350 000<\/span> Follower auf Twitter. Seine Posts finden \u00f6fter mal mehr als eine Million Leser. Allerdings kennzeichnet Wolf seinen Account deutlich mit dem Satz: &#8222;Dieses ist keine\u00a0ORF-Seite&#8220;.<\/p>\n<div id=\"contentGarden\">\u00a0Auff\u00e4llig ist, dass die Sache an Momentum gewinnt, nachdem Wolf k\u00fcrzlich den scheidenden <a href=\"http:\/\/www.sueddeutsche.de\/politik\/landeshauptmann-von-niederoesterreich-erwin-proell-vom-fall-eines-der-maechtigsten-politiker-oesterreichs-1.3337286\">Landeshauptmann von Nieder\u00f6sterreich, Erwin Pr\u00f6ll (\u00d6VP)<\/a>, interviewte. Der Fragende war hervorragend vorbereitet und hakte x-mal nach. Der Gast, seit einem Vierteljahrhundert wichtiger Machtfaktor im Land und zuletzt wegen einer intransparenten Stiftung, die auf seinen Namen l\u00e4uft, unter Beschuss, war schlecht vorbereitet, beleidigt und nach dem Gespr\u00e4ch extrem ver\u00e4rgert. Im Wochenmagazin <i>News<\/i> drohte er kurz darauf, er verstehe den Generaldirektor nicht, weil der offenbar nicht imstande sei, &#8222;solche Strukturen&#8220; zu kontrollieren. Es sei notwendig, &#8222;auch mit demokratischen M\u00f6glichkeiten im ORF nach dem Rechten zu sehen&#8220;. Das war eine klare\u00a0Kampfansage.<\/div>\n<p>Der Redakteursrat hat sich am Montag vor Armin Wolf und gegen Online-Chef Prantner gestellt. Man sei \u00fcberrascht, dass sich die Technische Redaktion f\u00fcr journalistische Inhalte zust\u00e4ndig f\u00fchle: &#8222;Wollen Sie ernsthaft einen R\u00fcckfall in die Zeiten, als Journalisten ihre Fragen erst bei Politikern einreichen mussten oder ihnen gar vorgeschrieben wurde, was gefragt werden\u00a0musste?&#8220;<\/p>\n<figure class=\"teaserable-layout teaserable-layout--image\"><figcaption>\n<h3 class=\"teaserable-layout__title\">Pl\u00e4doyer f\u00fcr das Kulturgut Zeitung<\/h3>\n<p><a href=\"http:\/\/www.sueddeutsche.de\/medien\/orf-moderator-armin-wolf-schreibt-bestseller-plaedoyer-fuer-das-kulturgut-zeitung-1.1651753\"><span class=\"teaserable-layout__abstract\"> Liebeserkl\u00e4rung an den eigenen Beruf: Der bekannteste Journalist \u00d6sterreichs, Armin Wolf, hat aufgeschrieben, warum Zeitungen und Fernsehen wichtig sind. Und das, obwohl immer weniger Menschen diese altmodischen Medien nutzen. Seine Analyse ist im Nachbarland jetzt ein Bestseller. <\/span> <span class=\"teaserable-layout__authors\">Von Cathrin Kahlweit, Wien<\/span> <\/a><\/p>\n<\/figcaption><figcaption><a href=\"http:\/\/www.sueddeutsche.de\/medien\/orf-moderator-armin-wolf-schreibt-bestseller-plaedoyer-fuer-das-kulturgut-zeitung-1.1651753\"><span class=\"teaserable-layout__more\">mehr&#8230;<\/span> <\/a><\/figcaption><figcaption>NB. Studierende berichten, <strong>dass sich Dr. Armin Wolf akribisch f\u00fcr seine Sendung vorbereitet, und zweifellos ist er als Journalist unbestechlich<\/strong>.\u00a0Manchmal \u00e4u\u00dferten wir\u00a0in der Medienkultur neben gro\u00dfer Hochachtung f\u00fcr Armin Wolf auch Bedenken zu seinem Stil.\u00a0Aber er darf\u00a0den fr\u00fcheren Bundeskanzler nach\u00a0L\u00fccken im\u00a0\u00a0Lebenslauf\u00a0fragen! \u00a0Da gab dieser vor,\u00a0Jus studiert zu haben und es bleibt unklar,\u00a0ob er \u00fcberhaupt eine einzige Vorlesung besucht hat oder gar eine\u00a0Jus-Pr\u00fcfung abgelegt habe.\u00a0Das ist wirklich\u00a0 mehr als\u00a0peinlich.\u00a0\u00a0<\/figcaption><\/figure>\n<p>Ein Buchtipp:\u00a0 Armin Wolf, Wozu brauchen wir noch Journalisten? Picus Verlag,\u00a0. 2013. Umfang: 142 p. \u00a0Entstanden aus Vorlesungen an der Univ. Wien 2012.<\/p>\n<\/section>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gastbeitrag: S\u00fcddeutsche Zeitung\u00a0 24. April 2017, 18:58 Uhr \u00a0ORF-Wolf zu kritisch, zu hartn\u00e4ckig F\u00fcr die &#8222;ORF-Sommergespr\u00e4che&#8220; besuchte Armin Wolf 2016 jeweils montags Parteivorsitzende dort, wo sie aufgewachsen sind. Was anderswo als gute journalistische Arbeit gilt, bringt ORF-Moderator Armin Wolf bei seinem Sender in Schwierigkeiten. Von Cathrin Kahlweit \u00a0Gerade erst hat sich der \u00d6sterreichische Rundfunk (ORF) &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/\" class=\"more-link\"><span class=\"screen-reader-text\">Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,1,10,13],"tags":[1677,2006,1932,2005,2007,1682,1396,1328],"class_list":["post-3709","post","type-post","status-publish","format-standard","hentry","category-gastbeitraege","category-allgemein","category-medienkritik","category-medienpolitik","tag-armin-wolf","tag-cathrin-kahlweit","tag-erwin-proell","tag-kritik-an-armin-wolf","tag-orf-interna","tag-roland-brunhofer","tag-sueddeutsche-zeitung","tag-zib-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"Gastbeitrag: S\u00fcddeutsche Zeitung\u00a0 24. April 2017, 18:58 Uhr \u00a0ORF-Wolf zu kritisch, zu hartn\u00e4ckig F\u00fcr die &#8222;ORF-Sommergespr\u00e4che&#8220; besuchte Armin Wolf 2016 jeweils montags Parteivorsitzende dort, wo sie aufgewachsen sind. Was anderswo als gute journalistische Arbeit gilt, bringt ORF-Moderator Armin Wolf bei seinem Sender in Schwierigkeiten. Von Cathrin Kahlweit \u00a0Gerade erst hat sich der \u00d6sterreichische Rundfunk (ORF) &hellip; Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-25T07:33:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-29T10:01:37+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/940x528?v=1493044623000\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung\",\"datePublished\":\"2017-04-25T07:33:42+00:00\",\"dateModified\":\"2017-04-29T10:01:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/\"},\"wordCount\":840,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/media-cdn.sueddeutsche.de\\\/image\\\/sz.1.3477037\\\/940x528?v=1493044623000\",\"keywords\":[\"Armin Wolf\",\"Cathrin Kahlweit\",\"Erwin Pr\u00f6ll\",\"Kritik an Armin Wolf\",\"ORF Interna\",\"Roland Brunhofer\",\"S\u00fcddeutsche Zeitung\",\"ZIB 2\"],\"articleSection\":[\"Gastbeitr\u00e4ge\",\"J\u00dcNGSTE BEITR\u00c4GE\",\"Medienkritik\",\"Medienpolitik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/\",\"name\":\"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/media-cdn.sueddeutsche.de\\\/image\\\/sz.1.3477037\\\/940x528?v=1493044623000\",\"datePublished\":\"2017-04-25T07:33:42+00:00\",\"dateModified\":\"2017-04-29T10:01:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/#primaryimage\",\"url\":\"http:\\\/\\\/media-cdn.sueddeutsche.de\\\/image\\\/sz.1.3477037\\\/940x528?v=1493044623000\",\"contentUrl\":\"http:\\\/\\\/media-cdn.sueddeutsche.de\\\/image\\\/sz.1.3477037\\\/940x528?v=1493044623000\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/","og_locale":"de_DE","og_type":"article","og_title":"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung | Vereinigung f\u00fcr Medienkultur","og_description":"Gastbeitrag: S\u00fcddeutsche Zeitung\u00a0 24. April 2017, 18:58 Uhr \u00a0ORF-Wolf zu kritisch, zu hartn\u00e4ckig F\u00fcr die &#8222;ORF-Sommergespr\u00e4che&#8220; besuchte Armin Wolf 2016 jeweils montags Parteivorsitzende dort, wo sie aufgewachsen sind. Was anderswo als gute journalistische Arbeit gilt, bringt ORF-Moderator Armin Wolf bei seinem Sender in Schwierigkeiten. Von Cathrin Kahlweit \u00a0Gerade erst hat sich der \u00d6sterreichische Rundfunk (ORF) &hellip; Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2017-04-25T07:33:42+00:00","article_modified_time":"2017-04-29T10:01:37+00:00","og_image":[{"url":"http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/940x528?v=1493044623000","type":"","width":"","height":""}],"author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung","datePublished":"2017-04-25T07:33:42+00:00","dateModified":"2017-04-29T10:01:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/"},"wordCount":840,"commentCount":0,"image":{"@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/#primaryimage"},"thumbnailUrl":"http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/940x528?v=1493044623000","keywords":["Armin Wolf","Cathrin Kahlweit","Erwin Pr\u00f6ll","Kritik an Armin Wolf","ORF Interna","Roland Brunhofer","S\u00fcddeutsche Zeitung","ZIB 2"],"articleSection":["Gastbeitr\u00e4ge","J\u00dcNGSTE BEITR\u00c4GE","Medienkritik","Medienpolitik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/","url":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/","name":"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/#primaryimage"},"image":{"@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/#primaryimage"},"thumbnailUrl":"http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/940x528?v=1493044623000","datePublished":"2017-04-25T07:33:42+00:00","dateModified":"2017-04-29T10:01:37+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/#primaryimage","url":"http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/940x528?v=1493044623000","contentUrl":"http:\/\/media-cdn.sueddeutsche.de\/image\/sz.1.3477037\/940x528?v=1493044623000"},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/armin-wolf-vor-abloese-beitrag-in-sueddeutscher-zeitung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Armin Wolf vor Abl\u00f6se? Beitrag in S\u00fcddeutscher Zeitung"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/3709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=3709"}],"version-history":[{"count":9,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/3709\/revisions"}],"predecessor-version":[{"id":3732,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/3709\/revisions\/3732"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=3709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=3709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=3709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}