{"id":3523,"date":"2017-02-26T13:10:35","date_gmt":"2017-02-26T11:10:35","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=3523"},"modified":"2017-02-26T13:35:38","modified_gmt":"2017-02-26T11:35:38","slug":"eu-kritik-krone-leserbriefe","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/","title":{"rendered":"EU-Kritik: &#8222;Krone&#8220;- Leserbriefe"},"content":{"rendered":"<h5>Hans H\u00f6gl<\/h5>\n<p>Ein Dorf-B\u00fcrgermeister\u00a0warnte mir gegen\u00fcber vor\u00a0dem langfristig\u00a0<strong>bedenklichen Einfluss der EU-Kritik in der &#8222;<em>Krone&#8220;<\/em><\/strong>. Es sei nicht gut,\u00a0\u00a0die EU-Negativ-Kampagne\u00a0der gr\u00f6\u00dften\u00a0Boulevard-Zeitung \u00d6sterreichs \u00a0einfachhin zu ignorieren. Ob nicht\u00a0einmal grunds\u00e4tzlich\u00a0 von\u00a0EU-Bef\u00fcrwortern\u00a0mit der\u00a0<em>Krone<\/em>-Redaktion\u00a0 das Gespr\u00e4ch zu suchen w\u00e4re?\u00a0\u00a0Meiner Kenntnis nach\u00a0erreicht\u00a0das &#8222;Haus des Europ\u00e4ischen Parlaments&#8220; in Wien\u00a0\u00a0bei Vortr\u00e4gen 6 0 &#8211; 80 Personen, \u00a0und ein Verantwortlicher dieser Institution findet einen Kontakt zur &#8222;Krone&#8220; \u00fcberfl\u00fcssig, obwohl die\u00a0Leserbriefspalte der <em>Krone<\/em> zum &#8222;EU-Theater&#8220; von Millionen gelesen wird. Hierin wird die\u00a0Europ\u00e4ischen Gemeinschaft\u00a0 ausschlie\u00dflich negativ punziert.\u00a0Ein\u00a0Gespr\u00e4ch\u00a0wird\u00a0ja keine direkte Antwort sein &#8211;\u00a0\u00a0\u00a0auf\u00a0einen e i n z e l n e n\u00a0\u00a0 uns\u00e4glichen Blog oder Leserbrief wie im Folgenden:<\/p>\n<p>So schreibt\u00a0heute im Blick auf die\u00a0Wahl von Donald Trump ein Herr Heinz Vielgrader aus Rappoltenkirchen vom &#8222;aufgescheuchten H\u00fchnerstall&#8220; des Br\u00fcsseler &#8222;Linksb\u00fcrokraten-Palastes&#8220; . Der FP\u00d6-Mann Herr Vielgrader wird im Telefonbuch\u00a0d i r e k t\u00a0\u00a0\u00a0angef\u00fchrt.\u00a0 Auch die anderen EU-Kritiker\u00a0dieser Sonntagsausgabe:\u00a0 Gerhard Forgatsch, Monika Ambros (beide Wien) und Christian Mitter aus Utzenaich finden sich im Telefonbuch. Es wird ja\u00a0manchmal vermutet,\u00a0dass\u00a0Leserbriefe von der Redaktion selbst verfasst sind.<\/p>\n<p>Schon vor mehreren\u00a0Jahren wurde festgestellt, dass 1812 &#8222;Krone&#8220;-Leserbriefe von nur 18 Schreibern verfasst wurden.\u00a0\u00a0Herr Vielgrader verfasste im Schnitt alle vier bis f\u00fcnf\u00a0Tage einen Leserbrief.\u00a0\u00a0Spitzenreiter Franz Weinpolter erscheint alle zwei Tage.\u00a0Das elektronische Zeitungsarchiv der APA fand\u00a0Herrn Weinpolter im\u00a0Zeitraum von drei Jahren\u00a0 608 Mal.<\/p>\n<p>&nbsp;<\/p>\n<h6 class=\"info\"><\/h6>\n<div class=\"socialsharing\"><\/div>\n<div class=\"clear\"><\/div>\n<div id=\"content-main\" class=\"section\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hans H\u00f6gl Ein Dorf-B\u00fcrgermeister\u00a0warnte mir gegen\u00fcber vor\u00a0dem langfristig\u00a0bedenklichen Einfluss der EU-Kritik in der &#8222;Krone&#8220;. Es sei nicht gut,\u00a0\u00a0die EU-Negativ-Kampagne\u00a0der gr\u00f6\u00dften\u00a0Boulevard-Zeitung \u00d6sterreichs \u00a0einfachhin zu ignorieren. Ob nicht\u00a0einmal grunds\u00e4tzlich\u00a0 von\u00a0EU-Bef\u00fcrwortern\u00a0mit der\u00a0Krone-Redaktion\u00a0 das Gespr\u00e4ch zu suchen w\u00e4re?\u00a0\u00a0Meiner Kenntnis nach\u00a0erreicht\u00a0das &#8222;Haus des Europ\u00e4ischen Parlaments&#8220; in Wien\u00a0\u00a0bei Vortr\u00e4gen 6 0 &#8211; 80 Personen, \u00a0und ein Verantwortlicher dieser Institution findet einen &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/\" class=\"more-link\"><span class=\"screen-reader-text\">EU-Kritik: &#8222;Krone&#8220;- Leserbriefe<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,11,20,19],"tags":[1786,1793,1790,1796,1792,1789,1363,1788,1785,1791,1794,1795],"class_list":["post-3523","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-medien_politik_wirtschaft","category-medienverantwortung_medienrecht","category-studien_rezensionen","tag-eu-theater-krone-leserspalte","tag-bruessel","tag-buergermeister-warnt","tag-dorf-buergermeister","tag-eu-kritik","tag-fpoe-mann-leserbrief-schreiber","tag-haus-des-europaeischen-parlaments","tag-ignorieren-von-massenblatt","tag-krone-leserbriefe-zur-eu","tag-leserbriefe-statistik","tag-rappoltenkirchen","tag-sieghartskirchen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EU-Kritik: &quot;Krone&quot;- Leserbriefe | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EU-Kritik: &quot;Krone&quot;- Leserbriefe | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"Hans H\u00f6gl Ein Dorf-B\u00fcrgermeister\u00a0warnte mir gegen\u00fcber vor\u00a0dem langfristig\u00a0bedenklichen Einfluss der EU-Kritik in der &#8222;Krone&#8220;. Es sei nicht gut,\u00a0\u00a0die EU-Negativ-Kampagne\u00a0der gr\u00f6\u00dften\u00a0Boulevard-Zeitung \u00d6sterreichs \u00a0einfachhin zu ignorieren. Ob nicht\u00a0einmal grunds\u00e4tzlich\u00a0 von\u00a0EU-Bef\u00fcrwortern\u00a0mit der\u00a0Krone-Redaktion\u00a0 das Gespr\u00e4ch zu suchen w\u00e4re?\u00a0\u00a0Meiner Kenntnis nach\u00a0erreicht\u00a0das &#8222;Haus des Europ\u00e4ischen Parlaments&#8220; in Wien\u00a0\u00a0bei Vortr\u00e4gen 6 0 &#8211; 80 Personen, \u00a0und ein Verantwortlicher dieser Institution findet einen &hellip; EU-Kritik: &#8222;Krone&#8220;- Leserbriefe weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-26T11:10:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-26T11:35:38+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/eu-kritik-krone-leserbriefe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/eu-kritik-krone-leserbriefe\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"EU-Kritik: &#8222;Krone&#8220;- Leserbriefe\",\"datePublished\":\"2017-02-26T11:10:35+00:00\",\"dateModified\":\"2017-02-26T11:35:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/eu-kritik-krone-leserbriefe\\\/\"},\"wordCount\":260,\"commentCount\":2,\"keywords\":[\"\\\"EU-Theater\\\" -\\\"Krone\\\"-Leserspalte\",\"Br\u00fcssel\",\"B\u00fcrgermeister warnt\",\"Dorf-B\u00fcrgermeister\",\"EU-Kritik\",\"FP\u00d6-Mann Leserbrief-Schreiber\",\"Haus des Europ\u00e4ischen Parlaments\",\"Ignorieren von Massenblatt?\",\"Krone-Leserbriefe zur EU\",\"Leserbriefe -Statistik\",\"Rappoltenkirchen\",\"Sieghartskirchen\"],\"articleSection\":[\"J\u00dcNGSTE BEITR\u00c4GE\",\"Medien und Politik \\\/ Wirtschaft\",\"Medienverantwortung \\\/ Medienrecht\",\"Studien \\\/ Rezensionen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/eu-kritik-krone-leserbriefe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/eu-kritik-krone-leserbriefe\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/eu-kritik-krone-leserbriefe\\\/\",\"name\":\"EU-Kritik: \\\"Krone\\\"- Leserbriefe | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2017-02-26T11:10:35+00:00\",\"dateModified\":\"2017-02-26T11:35:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/eu-kritik-krone-leserbriefe\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/eu-kritik-krone-leserbriefe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/eu-kritik-krone-leserbriefe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EU-Kritik: &#8222;Krone&#8220;- Leserbriefe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EU-Kritik: \"Krone\"- Leserbriefe | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/","og_locale":"de_DE","og_type":"article","og_title":"EU-Kritik: \"Krone\"- Leserbriefe | Vereinigung f\u00fcr Medienkultur","og_description":"Hans H\u00f6gl Ein Dorf-B\u00fcrgermeister\u00a0warnte mir gegen\u00fcber vor\u00a0dem langfristig\u00a0bedenklichen Einfluss der EU-Kritik in der &#8222;Krone&#8220;. Es sei nicht gut,\u00a0\u00a0die EU-Negativ-Kampagne\u00a0der gr\u00f6\u00dften\u00a0Boulevard-Zeitung \u00d6sterreichs \u00a0einfachhin zu ignorieren. Ob nicht\u00a0einmal grunds\u00e4tzlich\u00a0 von\u00a0EU-Bef\u00fcrwortern\u00a0mit der\u00a0Krone-Redaktion\u00a0 das Gespr\u00e4ch zu suchen w\u00e4re?\u00a0\u00a0Meiner Kenntnis nach\u00a0erreicht\u00a0das &#8222;Haus des Europ\u00e4ischen Parlaments&#8220; in Wien\u00a0\u00a0bei Vortr\u00e4gen 6 0 &#8211; 80 Personen, \u00a0und ein Verantwortlicher dieser Institution findet einen &hellip; EU-Kritik: &#8222;Krone&#8220;- Leserbriefe weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2017-02-26T11:10:35+00:00","article_modified_time":"2017-02-26T11:35:38+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"EU-Kritik: &#8222;Krone&#8220;- Leserbriefe","datePublished":"2017-02-26T11:10:35+00:00","dateModified":"2017-02-26T11:35:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/"},"wordCount":260,"commentCount":2,"keywords":["\"EU-Theater\" -\"Krone\"-Leserspalte","Br\u00fcssel","B\u00fcrgermeister warnt","Dorf-B\u00fcrgermeister","EU-Kritik","FP\u00d6-Mann Leserbrief-Schreiber","Haus des Europ\u00e4ischen Parlaments","Ignorieren von Massenblatt?","Krone-Leserbriefe zur EU","Leserbriefe -Statistik","Rappoltenkirchen","Sieghartskirchen"],"articleSection":["J\u00dcNGSTE BEITR\u00c4GE","Medien und Politik \/ Wirtschaft","Medienverantwortung \/ Medienrecht","Studien \/ Rezensionen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/","url":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/","name":"EU-Kritik: \"Krone\"- Leserbriefe | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2017-02-26T11:10:35+00:00","dateModified":"2017-02-26T11:35:38+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/eu-kritik-krone-leserbriefe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"EU-Kritik: &#8222;Krone&#8220;- Leserbriefe"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/3523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=3523"}],"version-history":[{"count":7,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/3523\/revisions"}],"predecessor-version":[{"id":3529,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/3523\/revisions\/3529"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=3523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=3523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=3523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}