{"id":2701,"date":"2016-04-08T10:33:16","date_gmt":"2016-04-08T08:33:16","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=2701"},"modified":"2016-04-08T10:33:16","modified_gmt":"2016-04-08T08:33:16","slug":"panama-papers-eine-etwas-andere-sicht","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/","title":{"rendered":"Panama Papers: Eine etwas andere Sicht.."},"content":{"rendered":"<h2 data-ft=\"{&quot;tn&quot;:&quot;C&quot;}\"><span style=\"color: #3366ff;\"><strong><b>Oh wie sch\u00f6n ist Panama<\/b><\/strong><\/span><\/h2>\n<p>Oskar Lafontaine*<\/p>\n<p>Panama ist ein Steuerparadies. Die <strong>Reichen und Sch\u00f6nen dieser Welt<\/strong> benutzen dieses Paradies, um sich davor zu dr\u00fccken, Steuern zu zahlen. 2013 wurden in unserer Presse noch <strong>deutsche Miliard\u00e4re<\/strong> genannt, die Firmen in Panama hatten: <strong>Pi\u00ebch, Porsche, Quandt, Burda, von Finck<\/strong> und so weiter. Nat\u00fcrlich haben alle versichert, dass sie davon entweder nichts w\u00fcssten, oder dass alles v\u00f6llig legal sei. <strong>Heute tauchen merkw\u00fcrdigerweise diese Namen nicht mehr auf. Auch reiche US-B\u00fcrger sind bisher nicht genannt worden.<\/strong> Im Vordergrund steht die Berichterstattung \u00fcber den russischen Pr\u00e4sidenten <strong>Putin<\/strong>, den ukrainischen Pr\u00e4sidenten Poroschenko, den s\u00fcdafrikanischen Pr\u00e4sidenten Zuma und den isl\u00e4ndischen Premier Gunnlaugsson.<\/p>\n<p><strong>Ist doch merkw\u00fcrdig, oder?<\/strong> Dazu schreibt der ehemalige britische Diplomat Craig Murray: \u201eLeider hat der Whistleblower, dem wir die Dokumente zu verdanken haben, den schrecklichen <strong>Fehler gemacht, sich an die westlichen Massenmedien zu wenden<\/strong>, um die Daten zu publizieren&#8230; Da rechnen Sie mal lieber nicht mit einer schonungslosen Offenlegung des westlichen Kapitalismus. <strong>Die dreckigen Geheimnisse der westlichen Unternehmen werden auch weiterhin verschlossen bleiben.<\/strong> Erwarten Sie lieber Sch\u00fcsse in Richtung Russland, Iran und Syrien und einige kleine &#8218;Alibisch\u00fcsse&#8216; auf kleinere westliche L\u00e4nder wie Island&#8230; <strong>Was w\u00e4re passiert, wenn man die Daten nach jedem Unternehmen durchsucht h\u00e4tte, das an den B\u00f6rsen des Westens gelistet ist und nach jedem westlichen Million\u00e4r?\u201c<\/strong><\/p>\n<p>Jetzt ist das \u00fcbliche Get\u00f6se bei den Wirtschaftssystem-Parteien wieder gro\u00df. Wie schon 2013. Wetten, dass alle darauf setzen, dass <strong>das Thema bald wieder in der Versenkung<\/strong> verschwindet? Man kennt sich doch, und die Parteispenden sind ja auch nicht zu verachten.<\/p>\n<ul>\n<li><em><strong>Oskar Lafontaine<\/strong>, deutscher Politiker (fr\u00fcher SPD, jetzt Die Linke) und Publizist, Ex-Ministerpr\u00e4sident, Ex-Finanzminister.<\/em><\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><u>http:\/\/www.nachdenkseiten.de\/?p=32707<\/u><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oh wie sch\u00f6n ist Panama Oskar Lafontaine* Panama ist ein Steuerparadies. Die Reichen und Sch\u00f6nen dieser Welt benutzen dieses Paradies, um sich davor zu dr\u00fccken, Steuern zu zahlen. 2013 wurden in unserer Presse noch deutsche Miliard\u00e4re genannt, die Firmen in Panama hatten: Pi\u00ebch, Porsche, Quandt, Burda, von Finck und so weiter. Nat\u00fcrlich haben alle versichert, &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/\" class=\"more-link\"><span class=\"screen-reader-text\">Panama Papers: Eine etwas andere Sicht..<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,15,11,10],"tags":[628,627,48,630,629],"class_list":["post-2701","post","type-post","status-publish","format-standard","hentry","category-berichte_analysen","category-gastbeitraege","category-medien_politik_wirtschaft","category-medienkritik","tag-deutsche-milliardaere","tag-panama-papers","tag-putin","tag-reiche-us-buerger","tag-westliche-massenmedien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Panama Papers: Eine etwas andere Sicht.. | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panama Papers: Eine etwas andere Sicht.. | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"Oh wie sch\u00f6n ist Panama Oskar Lafontaine* Panama ist ein Steuerparadies. Die Reichen und Sch\u00f6nen dieser Welt benutzen dieses Paradies, um sich davor zu dr\u00fccken, Steuern zu zahlen. 2013 wurden in unserer Presse noch deutsche Miliard\u00e4re genannt, die Firmen in Panama hatten: Pi\u00ebch, Porsche, Quandt, Burda, von Finck und so weiter. Nat\u00fcrlich haben alle versichert, &hellip; Panama Papers: Eine etwas andere Sicht.. weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-08T08:33:16+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/panama-papers-eine-etwas-andere-sicht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/panama-papers-eine-etwas-andere-sicht\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"Panama Papers: Eine etwas andere Sicht..\",\"datePublished\":\"2016-04-08T08:33:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/panama-papers-eine-etwas-andere-sicht\\\/\"},\"wordCount\":302,\"commentCount\":1,\"keywords\":[\"deutsche Milliard\u00e4re\",\"Panama Papers\",\"Putin\",\"reiche US-B\u00fcrger\",\"westliche Massenmedien\"],\"articleSection\":[\"BERICHTE \\\/ ANALYSEN\",\"Gastbeitr\u00e4ge\",\"Medien und Politik \\\/ Wirtschaft\",\"Medienkritik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/panama-papers-eine-etwas-andere-sicht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/panama-papers-eine-etwas-andere-sicht\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/panama-papers-eine-etwas-andere-sicht\\\/\",\"name\":\"Panama Papers: Eine etwas andere Sicht.. | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2016-04-08T08:33:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/panama-papers-eine-etwas-andere-sicht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/panama-papers-eine-etwas-andere-sicht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/panama-papers-eine-etwas-andere-sicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Panama Papers: Eine etwas andere Sicht..\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Panama Papers: Eine etwas andere Sicht.. | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/","og_locale":"de_DE","og_type":"article","og_title":"Panama Papers: Eine etwas andere Sicht.. | Vereinigung f\u00fcr Medienkultur","og_description":"Oh wie sch\u00f6n ist Panama Oskar Lafontaine* Panama ist ein Steuerparadies. Die Reichen und Sch\u00f6nen dieser Welt benutzen dieses Paradies, um sich davor zu dr\u00fccken, Steuern zu zahlen. 2013 wurden in unserer Presse noch deutsche Miliard\u00e4re genannt, die Firmen in Panama hatten: Pi\u00ebch, Porsche, Quandt, Burda, von Finck und so weiter. Nat\u00fcrlich haben alle versichert, &hellip; Panama Papers: Eine etwas andere Sicht.. weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2016-04-08T08:33:16+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"Panama Papers: Eine etwas andere Sicht..","datePublished":"2016-04-08T08:33:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/"},"wordCount":302,"commentCount":1,"keywords":["deutsche Milliard\u00e4re","Panama Papers","Putin","reiche US-B\u00fcrger","westliche Massenmedien"],"articleSection":["BERICHTE \/ ANALYSEN","Gastbeitr\u00e4ge","Medien und Politik \/ Wirtschaft","Medienkritik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/","url":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/","name":"Panama Papers: Eine etwas andere Sicht.. | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2016-04-08T08:33:16+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/panama-papers-eine-etwas-andere-sicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Panama Papers: Eine etwas andere Sicht.."}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/2701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=2701"}],"version-history":[{"count":1,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/2701\/revisions"}],"predecessor-version":[{"id":2702,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/2701\/revisions\/2702"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=2701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=2701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=2701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}