{"id":12750,"date":"2023-12-13T08:07:41","date_gmt":"2023-12-13T07:07:41","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=12750"},"modified":"2023-12-13T18:42:48","modified_gmt":"2023-12-13T17:42:48","slug":"kriegsbilder-und-kinder","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/","title":{"rendered":"Kriegsbilder und Kinder"},"content":{"rendered":"<p>Kriegsbilder auf Bildschirmen k\u00f6nnen Kinder krank machen. Das geht aus einem Beitrag der Internet-Plattform &#8222;Perspective Daily&#8220; hervor.<\/p>\n<p>Hans H\u00f6gl<br \/>\n(pr\u00e4sentiert einen Ausschnitt aus dem Blog)<\/p>\n<p>&#8222;Pl\u00f6tzlich ist der Krieg ganz nah, in aller Deutlichkeit. Per Social Media landen drastische Bilder und Videos direkt auf den Smartphones, auch auf den Ger\u00e4ten von Kindern und Jugendlichen. Wie im Fall der Schwestern Charly und Nele Schneider, 13 und 16 Jahre alt. Seit dem Ukrainekrieg, dem Terrorangriff der Hamas auf Israel und in dessen Folge dem Krieg in Gaza bekommen die beiden immer wieder verst\u00f6rende Inhalte zu sehen. Die M\u00e4dchen haben ihren Eltern von Kriegsszenen auf den Smartphones der Mitsch\u00fcler:innen erz\u00e4hlt. Laut Mutter Anne Schneider ist es aber auch oft schon problematisch, wenn die Familie zusammen die Tagesschau guckt: \u00bbDie Bilder sind auch nicht ohne.\u00ab<\/p>\n<p>Was machen die Kriegsszenen mit jungen Menschen \u2013 die zudem in einer Welt aufwachsen, die von Nachrichten zur Klimakrise, zur Coronapandemie und zu den aktuellen Kriegen gepr\u00e4gt ist? K\u00f6nnen Eltern sie \u00fcberhaupt vor Gewaltinhalten sch\u00fctzen, wenn diese praktisch pausenlos in sozialen Medien unterwegs sind? Und wie arbeiten Familien im Ernstfall das Gesehene richtig auf?&#8220;<\/p>\n<p><em>Zitate aus &#8222;Perspective Daily&#8220;, ausgew\u00e4hlt von Hans H\u00f6gl<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kriegsbilder auf Bildschirmen k\u00f6nnen Kinder krank machen. Das geht aus einem Beitrag der Internet-Plattform &#8222;Perspective Daily&#8220; hervor. Hans H\u00f6gl (pr\u00e4sentiert einen Ausschnitt aus dem Blog) &#8222;Pl\u00f6tzlich ist der Krieg ganz nah, in aller Deutlichkeit. Per Social Media landen drastische Bilder und Videos direkt auf den Smartphones, auch auf den Ger\u00e4ten von Kindern und Jugendlichen. Wie &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/\" class=\"more-link\"><span class=\"screen-reader-text\">Kriegsbilder und Kinder<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[296,10230,9946,9123,10231],"class_list":["post-12750","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-kinder","tag-kriegsbilder","tag-perspective-daily","tag-smartphone","tag-social-media-mit-drastischen-blldern"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kriegsbilder und Kinder | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kriegsbilder und Kinder | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"Kriegsbilder auf Bildschirmen k\u00f6nnen Kinder krank machen. Das geht aus einem Beitrag der Internet-Plattform &#8222;Perspective Daily&#8220; hervor. Hans H\u00f6gl (pr\u00e4sentiert einen Ausschnitt aus dem Blog) &#8222;Pl\u00f6tzlich ist der Krieg ganz nah, in aller Deutlichkeit. Per Social Media landen drastische Bilder und Videos direkt auf den Smartphones, auch auf den Ger\u00e4ten von Kindern und Jugendlichen. Wie &hellip; Kriegsbilder und Kinder weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-13T07:07:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-13T17:42:48+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/kriegsbilder-und-kinder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/kriegsbilder-und-kinder\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"Kriegsbilder und Kinder\",\"datePublished\":\"2023-12-13T07:07:41+00:00\",\"dateModified\":\"2023-12-13T17:42:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/kriegsbilder-und-kinder\\\/\"},\"wordCount\":208,\"commentCount\":0,\"keywords\":[\"Kinder\",\"Kriegsbilder\",\"Perspective Daily\",\"Smartphone\",\"Social Media mit drastischen Blldern\"],\"articleSection\":[\"J\u00dcNGSTE BEITR\u00c4GE\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/kriegsbilder-und-kinder\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/kriegsbilder-und-kinder\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/kriegsbilder-und-kinder\\\/\",\"name\":\"Kriegsbilder und Kinder | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2023-12-13T07:07:41+00:00\",\"dateModified\":\"2023-12-13T17:42:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/kriegsbilder-und-kinder\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/kriegsbilder-und-kinder\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/kriegsbilder-und-kinder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kriegsbilder und Kinder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kriegsbilder und Kinder | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/","og_locale":"de_DE","og_type":"article","og_title":"Kriegsbilder und Kinder | Vereinigung f\u00fcr Medienkultur","og_description":"Kriegsbilder auf Bildschirmen k\u00f6nnen Kinder krank machen. Das geht aus einem Beitrag der Internet-Plattform &#8222;Perspective Daily&#8220; hervor. Hans H\u00f6gl (pr\u00e4sentiert einen Ausschnitt aus dem Blog) &#8222;Pl\u00f6tzlich ist der Krieg ganz nah, in aller Deutlichkeit. Per Social Media landen drastische Bilder und Videos direkt auf den Smartphones, auch auf den Ger\u00e4ten von Kindern und Jugendlichen. Wie &hellip; Kriegsbilder und Kinder weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2023-12-13T07:07:41+00:00","article_modified_time":"2023-12-13T17:42:48+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"Kriegsbilder und Kinder","datePublished":"2023-12-13T07:07:41+00:00","dateModified":"2023-12-13T17:42:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/"},"wordCount":208,"commentCount":0,"keywords":["Kinder","Kriegsbilder","Perspective Daily","Smartphone","Social Media mit drastischen Blldern"],"articleSection":["J\u00dcNGSTE BEITR\u00c4GE"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/","url":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/","name":"Kriegsbilder und Kinder | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2023-12-13T07:07:41+00:00","dateModified":"2023-12-13T17:42:48+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/kriegsbilder-und-kinder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Kriegsbilder und Kinder"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/12750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=12750"}],"version-history":[{"count":6,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/12750\/revisions"}],"predecessor-version":[{"id":12764,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/12750\/revisions\/12764"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=12750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=12750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=12750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}