{"id":12631,"date":"2023-11-09T20:41:57","date_gmt":"2023-11-09T19:41:57","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=12631"},"modified":"2023-11-10T16:38:35","modified_gmt":"2023-11-10T15:38:35","slug":"journalistische-sprachregelung","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/","title":{"rendered":"Journalistische Sprachregelung"},"content":{"rendered":"<p> \u201eGlossar Berichterstattung Nahostkonflikt. Zur internen Nutzung&#8220; ist der Titel eines dem &#8222;Nachdenkseiten&#8220;-Autor Albrecht M\u00fcller vorliegenden Papier der ARD. Ein Papier voll mit Sprachregelungen f\u00fcr Journalistinnen und Journalistinnen der deutschen \u00f6ffentlich-rechtlichen Anstalt. Ein demokratie- und medienpolitischer Skandal, so die Kritik. <\/p>\n<p>Albrecht M\u00fcller *<\/p>\n<p>Damit Sie dieses Papier schnell in H\u00e4nden haben, verzichte ich auf eine ausf\u00fchrliche Wiedergabe. Auf Kommentierung kann ich verzichten. Die Texte sprechen f\u00fcr sich selbst und gegen das Demokratieverst\u00e4ndnis der ARD:<\/p>\n<p>Auf den Seiten 3 und 4 lesen wir das Folgende:<\/p>\n<p>Glossar Berichterstattung Nahostkonflikt (zur internen Nutzung)<\/p>\n<p>Wie macht es die Tagesschau? (E-Mail-Ausz\u00fcge)<\/p>\n<p>\u201e(\u2026) nach unserem Austausch in der 10:30 Uhr heute noch mal ein Blick auf die Formulierungen in der Berichterstattung \u00fcber Nahost. Wie bereits gestern geschrieben, m\u00fcssen wir das von Tag zu Tag anschauen, beispielsweise ob und wie wir das Wort \u201eKrieg\u201c verwenden. Heute gibt es diese Hinweise und Bitten:<\/p>\n<p>Wir sprechen weiterhin von \u201eAngriff\/en aus Gaza auf Israel\u201c oder \u201eTerrorangriff\/e auf Israel\u201c. Es kann aber auch \u201eKrieg gegen Israel\u201c verwendet werden.<\/p>\n<p>Was unbedingt vermieden werden muss, sind Worte wie \u201eGewaltspirale\u201c \u2013 und auch \u201eEskalation in Nahost\u201c beschreibt die aktuelle Lage seit Samstag nicht ausreichend. Die Situation ist komplexer.<\/p>\n<p>Bitte passt auch auf wie wir das Wort \u201eAngriff\u201c genau verwenden: In dieser Situation sind es \u201eGegenangriffe von Israel auf Gaza\u201c. Es ist verk\u00fcrzt zu sagen oder schreiben \u201eAngriffe auf Israel und Gaza\u201c.\u201c<\/p>\n<p>(\u2026)<\/p>\n<p>\u201eAls Reminder zudem die Rundmail von gestern:<\/p>\n<p>Unsere AG Sprache besch\u00e4ftigt sich in diesen Tagen noch mal intensiv mit Begriffen und Beschreibungen zur Nahost-Berichterstattung. Bitte alle, die bei uns schreiben und oder moderieren einmal die Beispiele unten durchlesen. Damit vermeiden wir Missverst\u00e4ndnisse oder Fehler. Au\u00dferdem bei \u00dcbernahme von Agenturtexten bitte genau \u00fcberlegen, ob die Formulierungen von dpa und Co. korrekt sind. Die Kolleginnen und Kollegen machen auch nicht immer alles richtig\u2026\u201c<\/p>\n<p>(\u2026)<\/p>\n<p>\u201eHamas-\u201eK\u00e4mpfer\u201c bitte vermeiden!<\/p>\n<p>Wie bereits von der Chefredaktion festgelegt, sollten wir nicht euphemistisch von Hamas-\u201eK\u00e4mpfern\u201c, sondern von Terroristen schreiben und sprechen. Als Synonyme bieten sich \u201emilitante Islamisten\u201c, \u201emilitante Pal\u00e4stinenser\u201c. \u201eTerrormiliz\u201c oder \u00e4hnliches an.<\/p>\n<p>Die antisemitische Hamas wird international weitgehend als terroristische Organisation eingestuft.<\/p>\n<p>Auch unterscheidet die Hamas \u2013 im Gegensatz zur israelischen Armee \u2013 in ihren Aktionen nicht zwischen milit\u00e4rischen Zielen und Zivilisten. Erkl\u00e4rtes Ziel der Hamas ist vielmehr die \u201eVernichtung Israels\u201c. Dazu bedient sie sich terroristischer Mittel, etwa durch das Ver\u00fcben von Anschl\u00e4gen, wahllosen Raketenbeschuss und \u00e4hnliches.<\/p>\n<p>Gleiches gilt f\u00fcr Mitglieder des \u201eIslamischen Dschihad\u201c, die an dem Hamas-Angriff beteiligt sind.<\/p>\n<p>((Glossar Berichterstattung Nahostkonflikt (zur internen Nutzung)))<\/p>\n<p>Radikaler Islam, Islamismus, militanter Islamismus<\/p>\n<p>Die Hamas ist klar islamistisch ausgerichtet \u2013 ihr Ziel ist die Errichtung eines islamischen Staates.<\/p>\n<p>Dieses Ziel teilen aber auch islamistische Organisationen, die nicht auf Terror setzen \u2013 etwa die Muslimbr\u00fcder in \u00c4gypten oder die Ennahda-Partei in Tunesien. Die Hamas dagegen will dieses Ziel mit Gewalt durchsetzen. Wir empfehlen daher die Begriffe \u201emilitant-islamistisch\u201c oder \u201emilitante Islamisten\u201c. Den Begriff Islamisten solo zu setzen, ist aber nicht falsch.<\/p>\n<p>Bitte die \u201eGewaltspirale\u201c vermeiden<\/p>\n<p>Die Floskel sagt wenig aus und geht in der Regel an den Realit\u00e4ten vorbei. Im aktuellen Fall hat die Hamas Israel \u00fcberraschend angegriffen \u2013 wir sollten daher auch vom \u201eHamas-Angriff auf Israel\u201c oder vom \u201eAngriff auf Israel\u201c sprechen und schreiben.<\/p>\n<p>Aktion und Reaktion<\/p>\n<p>Mit der mutma\u00dflichen harten Reaktion der israelischen Armee wird sich in den kommenden Tagen der Fokus und damit auch unsere Berichterstattung auf den Gazastreifen und das Leid der dortigen Bev\u00f6lkerung verschieben. Wir sollten dabei aber nicht ausblenden, dass die Hamas den aktuellen Konflikt begonnen hat.<\/p>\n<p>Wer greift was an?<\/p>\n<p>Die israelische Armee fliegt als Reaktion Angriffe im Gaza-Streifen. Ziele waren in der Vergangenheit stets milit\u00e4rische Einrichtungen der Hamas. Oft sterben dabei viele Zivilisten \u2013 die Hamas nutzt diese oft als menschliche Schutzschilde. Dennoch sollten wir stets klarmachen, dass es sich in der Regel um Angriffe auf milit\u00e4rische Ziele handelt.<\/p>\n<p>In diesem Zusammenhang sollten wir auch auf die immer wieder auftauchenden euphemistischen \u201eLuftschl\u00e4ge\u201c verzichten. Es handelt sich um Angriffe mit Raketen und Kampfjets.<\/p>\n<p><em>*Albrecht M\u00fcller ist ein deutscher Volkswirt, Publizist und ehemaliger Politiker (SPD).<\/p>\n<p>Der Beitrag ist der kritischen Website &#8222;Nachdenkseiten&#8220; entnommen: https:\/\/www.nachdenkseiten.de\/?p=105894<\/em><\/p>\n<p>Zusatzbemerkung von Ex-ORF-Redakteur Udo Bachmair, hauptverantwortlich f\u00fcr die Vereinigung f\u00fcr Medienkultur: <\/p>\n<p>Ob es eine interne schriftliche Sprachregelung auch f\u00fcr (laut Redaktionsstatut) &#8222;eigenverantwortliche&#8220; ORF-Redakteure gibt, ist nicht bekannt. Das w\u00e4re wahrscheinlich nicht n\u00f6tig, denn viele ORF-JournalistInnen scheinen ohnehin im Sinne des Mainstreams in der Nahost- und auch der Ukrainekriegsberichterstattung zu &#8222;funktionieren&#8220;&#8230; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eGlossar Berichterstattung Nahostkonflikt. Zur internen Nutzung&#8220; ist der Titel eines dem &#8222;Nachdenkseiten&#8220;-Autor Albrecht M\u00fcller vorliegenden Papier der ARD. Ein Papier voll mit Sprachregelungen f\u00fcr Journalistinnen und Journalistinnen der deutschen \u00f6ffentlich-rechtlichen Anstalt. Ein demokratie- und medienpolitischer Skandal, so die Kritik. Albrecht M\u00fcller * Damit Sie dieses Papier schnell in H\u00e4nden haben, verzichte ich auf eine ausf\u00fchrliche &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/\" class=\"more-link\"><span class=\"screen-reader-text\">Journalistische Sprachregelung<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,15,1,11,18,10,13,20],"tags":[10138,10132,556,10133,10136,10137,10134,10140,452,10131,121,4157,10135,9284,10139],"class_list":["post-12631","post","type-post","status-publish","format-standard","hentry","category-berichte_analysen","category-gastbeitraege","category-allgemein","category-medien_politik_wirtschaft","category-medienkompetenz","category-medienkritik","category-medienpolitik","category-medienverantwortung_medienrecht","tag-ag-sprache","tag-albrecht-mueller","tag-ard","tag-demokratieverstaendnis","tag-gaza","tag-gewaltspirale","tag-glossar-berichterstattung-nahostkonflikt","tag-hamas","tag-israel","tag-journalistische-sprachregelung","tag-krieg","tag-nachdenkseiten","tag-nahost","tag-tagesschau","tag-uebernahme-von-agenturtexten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journalistische Sprachregelung | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journalistische Sprachregelung | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"\u201eGlossar Berichterstattung Nahostkonflikt. Zur internen Nutzung&#8220; ist der Titel eines dem &#8222;Nachdenkseiten&#8220;-Autor Albrecht M\u00fcller vorliegenden Papier der ARD. Ein Papier voll mit Sprachregelungen f\u00fcr Journalistinnen und Journalistinnen der deutschen \u00f6ffentlich-rechtlichen Anstalt. Ein demokratie- und medienpolitischer Skandal, so die Kritik. Albrecht M\u00fcller * Damit Sie dieses Papier schnell in H\u00e4nden haben, verzichte ich auf eine ausf\u00fchrliche &hellip; Journalistische Sprachregelung weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T19:41:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-10T15:38:35+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/journalistische-sprachregelung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/journalistische-sprachregelung\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"Journalistische Sprachregelung\",\"datePublished\":\"2023-11-09T19:41:57+00:00\",\"dateModified\":\"2023-11-10T15:38:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/journalistische-sprachregelung\\\/\"},\"wordCount\":747,\"commentCount\":1,\"keywords\":[\"AG Sprache\",\"Albrecht M\u00fcller\",\"ARD\",\"Demokratieverst\u00e4ndnis\",\"Gaza\",\"Gewaltspirale\",\"Glossar Berichterstattung Nahostkonflikt\",\"Hamas\",\"Israel\",\"journalistische Sprachregelung\",\"Krieg\",\"Nachdenkseiten\",\"Nahost\",\"Tagesschau\",\"\u00dcbernahme von Agenturtexten\"],\"articleSection\":[\"BERICHTE \\\/ ANALYSEN\",\"Gastbeitr\u00e4ge\",\"J\u00dcNGSTE BEITR\u00c4GE\",\"Medien und Politik \\\/ Wirtschaft\",\"Medienkompetenz\",\"Medienkritik\",\"Medienpolitik\",\"Medienverantwortung \\\/ Medienrecht\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/journalistische-sprachregelung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/journalistische-sprachregelung\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/journalistische-sprachregelung\\\/\",\"name\":\"Journalistische Sprachregelung | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2023-11-09T19:41:57+00:00\",\"dateModified\":\"2023-11-10T15:38:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/journalistische-sprachregelung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/journalistische-sprachregelung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/journalistische-sprachregelung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journalistische Sprachregelung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journalistische Sprachregelung | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/","og_locale":"de_DE","og_type":"article","og_title":"Journalistische Sprachregelung | Vereinigung f\u00fcr Medienkultur","og_description":"\u201eGlossar Berichterstattung Nahostkonflikt. Zur internen Nutzung&#8220; ist der Titel eines dem &#8222;Nachdenkseiten&#8220;-Autor Albrecht M\u00fcller vorliegenden Papier der ARD. Ein Papier voll mit Sprachregelungen f\u00fcr Journalistinnen und Journalistinnen der deutschen \u00f6ffentlich-rechtlichen Anstalt. Ein demokratie- und medienpolitischer Skandal, so die Kritik. Albrecht M\u00fcller * Damit Sie dieses Papier schnell in H\u00e4nden haben, verzichte ich auf eine ausf\u00fchrliche &hellip; Journalistische Sprachregelung weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2023-11-09T19:41:57+00:00","article_modified_time":"2023-11-10T15:38:35+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"Journalistische Sprachregelung","datePublished":"2023-11-09T19:41:57+00:00","dateModified":"2023-11-10T15:38:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/"},"wordCount":747,"commentCount":1,"keywords":["AG Sprache","Albrecht M\u00fcller","ARD","Demokratieverst\u00e4ndnis","Gaza","Gewaltspirale","Glossar Berichterstattung Nahostkonflikt","Hamas","Israel","journalistische Sprachregelung","Krieg","Nachdenkseiten","Nahost","Tagesschau","\u00dcbernahme von Agenturtexten"],"articleSection":["BERICHTE \/ ANALYSEN","Gastbeitr\u00e4ge","J\u00dcNGSTE BEITR\u00c4GE","Medien und Politik \/ Wirtschaft","Medienkompetenz","Medienkritik","Medienpolitik","Medienverantwortung \/ Medienrecht"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/","url":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/","name":"Journalistische Sprachregelung | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2023-11-09T19:41:57+00:00","dateModified":"2023-11-10T15:38:35+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/journalistische-sprachregelung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Journalistische Sprachregelung"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/12631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=12631"}],"version-history":[{"count":6,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/12631\/revisions"}],"predecessor-version":[{"id":12638,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/12631\/revisions\/12638"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=12631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=12631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=12631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}