{"id":10893,"date":"2022-05-01T09:52:56","date_gmt":"2022-05-01T08:52:56","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=10893"},"modified":"2022-05-02T17:51:58","modified_gmt":"2022-05-02T16:51:58","slug":"angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/","title":{"rendered":"Angstgef\u00fchle und Panik in der Moderne"},"content":{"rendered":"<p>Die fulminante Edvard-Munch Ausstellung in der Albertina in Wien genie\u00dft gro\u00dfe Aufmerksamkeit, im Besonderen das Bild &#8222;Der Schrei&#8220;. Es symbolisiert Angst- und Panik- Lebensgef\u00fchle auch in der Moderne &#8211; ob es um Klimaangst, Corona oder den Ukraine-Krieg geht. <\/p>\n<p>Hans H \u00f6 g l  <\/p>\n<p>Das Bild &#8222;Der Schrei&#8220; ist ein Extremausdruck von Angst, Panik, Schrecken. Nicht ein bestimmter Mensch zeigt das Entsetzen, sondern einer f\u00fcr alle. Ein Bild, aus der Lebensangst von Munch geboren, nimmt uns in die Existenzangst des K\u00fcnstlers hinein. Hier revoltiert Munch gegen den Naturalismus und Impressionismus,  und das Bild &#8222;Der Schrei&#8220; wird Ikone des Expressionismus- gestaltet 1893 und 1910 &#8211; ein Sinnbild unserer letzten Jahrhunderte mit schrecklichen Katastrophen und \u00c4ngsten und zwar auch in einer s\u00e4kularen, aufgekl\u00e4rten Welt, die nun seit mehreren hundert Jahren die Welt dominiert. <\/p>\n<p>Wer sich z.B. nicht nur mit den Verbrechen des Nazismus, sondern auch mit denen in Russlands Vergangenheit befasst, wie ich k\u00fcrzlich, findet die Brutalit\u00e4t und Menschenverachtung &#8211; schon am Ende der Franz\u00f6sischen Revolution und imitiert von Lenin in der Russischen Revolution und die systematisch geplanten Hungersn\u00f6te in der Ukraine um 1930 schon beim Lesen (!) unertr\u00e4glich. <\/p>\n<p>Warum dies so war, danach fragt der fr\u00fchere Maoist und franz\u00f6sische Spitzenhistoriker St\u00e9phane Courtois in dem im deutschsprachigen Raum kaum rezipierten,  beziehungsweise verdr\u00e4ngten Werk &#8222;Die Verbrechen des Kommunismus&#8220; p. 793-825 (1998 Piper). Und wie die Mannschaft um Putin heute in der Ukraine werkt, ist ebenso bedenklich wie die Brutalit\u00e4t des Westens &#8211; so im Irak und Chile und Vietnam  usw., obgleich sich der Westen so gern scheinheilig auf individuelle Menschenrechte beruft.   <\/p>\n<p>Im &#8222;Schrei&#8220; wird der Mensch Symbolfigur f\u00fcr das Sich-Verlieren des Einzelnen im Ganzen: Die Urangst der Gesellschaft am Beginn der Moderne.  <\/p>\n<p>Edvard Munch hat die Angstattacke beschrieben: Ich ging den Weg entlang mit zwei Freunden. Die Sonne ging unter. Der Himmel  wurde pl\u00f6tzlich  rot. Ich stand zitternd vor Angst. Und ich f\u00fchlte einen lauten, unendlichen Schrei durch die Natur. So beschreibt es Klaus Albrecht Schr\u00f6der, Direktor der Albertina. Das Interview findet sich im Massenblatt der &#8222;Krone&#8220;.  <\/p>\n<p>Die Ausstellung \u00fcber das Werk von Munch ist in Wien bis 19. Juni zu sehen &#8211; in chronologischer Reihenfolge &#8211; vor allem das Sp\u00e4twerk. Es werden auch thematisch \u00e4hnliche Werke anderer K\u00fcnstler gezeigt &#8211; so von  Andy Warhol, Miriam Cahn und Peter Doig. <\/p>\n<p>NB. Auff\u00e4llig ist: Ich habe drei Medien-Rezensionen vor mir. Das Bild &#8222;Der stumme Schrei&#8220; ist zwar abgebildet, doch nirgends findet sich ein Hinweis, dass dieses Bild selbst nicht in Wien ausgestellt wird.  Auf Nachfrage erfahre ich, dass es nicht entliehen wird. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die fulminante Edvard-Munch Ausstellung in der Albertina in Wien genie\u00dft gro\u00dfe Aufmerksamkeit, im Besonderen das Bild &#8222;Der Schrei&#8220;. Es symbolisiert Angst- und Panik- Lebensgef\u00fchle auch in der Moderne &#8211; ob es um Klimaangst, Corona oder den Ukraine-Krieg geht. Hans H \u00f6 g l Das Bild &#8222;Der Schrei&#8220; ist ein Extremausdruck von Angst, Panik, Schrecken. Nicht &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/\" class=\"more-link\"><span class=\"screen-reader-text\">Angstgef\u00fchle und Panik in der Moderne<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,12,19],"tags":[8645,8643,8641,444,8649,2848,8640,8647,8644,8648,8642,7844,8646,8650,8651],"class_list":["post-10893","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-medien_bildung_religion","category-studien_rezensionen","tag-der-schrei","tag-albertina-wien","tag-andy-warhol","tag-angst","tag-brutalitaet-in-russlands-vergangenheit","tag-die-krone","tag-edvard-munch","tag-expressionismus","tag-klaus-a-schroeder","tag-lebensgefuehl-in-der-moderne","tag-miriam-cahn-und-peter-doig","tag-panik","tag-schrecken","tag-stephane-courtois","tag-verbrechen-des-kommunismus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Angstgef\u00fchle und Panik in der Moderne | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angstgef\u00fchle und Panik in der Moderne | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"Die fulminante Edvard-Munch Ausstellung in der Albertina in Wien genie\u00dft gro\u00dfe Aufmerksamkeit, im Besonderen das Bild &#8222;Der Schrei&#8220;. Es symbolisiert Angst- und Panik- Lebensgef\u00fchle auch in der Moderne &#8211; ob es um Klimaangst, Corona oder den Ukraine-Krieg geht. Hans H \u00f6 g l Das Bild &#8222;Der Schrei&#8220; ist ein Extremausdruck von Angst, Panik, Schrecken. Nicht &hellip; Angstgef\u00fchle und Panik in der Moderne weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-01T08:52:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-02T16:51:58+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"Angstgef\u00fchle und Panik in der Moderne\",\"datePublished\":\"2022-05-01T08:52:56+00:00\",\"dateModified\":\"2022-05-02T16:51:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\\\/\"},\"wordCount\":442,\"commentCount\":0,\"keywords\":[\"\\\"Der Schrei\\\"\",\"Albertina Wien\",\"Andy Warhol\",\"Angst\",\"Brutalit\u00e4t in Russlands Vergangenheit\",\"Die Krone\",\"Edvard Munch\",\"Expressionismus\",\"Klaus A. Schr\u00f6der\",\"Lebensgef\u00fchl in der Moderne\",\"Miriam Cahn und Peter Doig\",\"Panik\",\"Schrecken\",\"St\u00e9phane Courtois\",\"Verbrechen des Kommunismus\"],\"articleSection\":[\"J\u00dcNGSTE BEITR\u00c4GE\",\"Medien und Bildung \\\/ Religion\",\"Studien \\\/ Rezensionen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\\\/\",\"name\":\"Angstgef\u00fchle und Panik in der Moderne | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2022-05-01T08:52:56+00:00\",\"dateModified\":\"2022-05-02T16:51:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Angstgef\u00fchle und Panik in der Moderne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Angstgef\u00fchle und Panik in der Moderne | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/","og_locale":"de_DE","og_type":"article","og_title":"Angstgef\u00fchle und Panik in der Moderne | Vereinigung f\u00fcr Medienkultur","og_description":"Die fulminante Edvard-Munch Ausstellung in der Albertina in Wien genie\u00dft gro\u00dfe Aufmerksamkeit, im Besonderen das Bild &#8222;Der Schrei&#8220;. Es symbolisiert Angst- und Panik- Lebensgef\u00fchle auch in der Moderne &#8211; ob es um Klimaangst, Corona oder den Ukraine-Krieg geht. Hans H \u00f6 g l Das Bild &#8222;Der Schrei&#8220; ist ein Extremausdruck von Angst, Panik, Schrecken. Nicht &hellip; Angstgef\u00fchle und Panik in der Moderne weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2022-05-01T08:52:56+00:00","article_modified_time":"2022-05-02T16:51:58+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"Angstgef\u00fchle und Panik in der Moderne","datePublished":"2022-05-01T08:52:56+00:00","dateModified":"2022-05-02T16:51:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/"},"wordCount":442,"commentCount":0,"keywords":["\"Der Schrei\"","Albertina Wien","Andy Warhol","Angst","Brutalit\u00e4t in Russlands Vergangenheit","Die Krone","Edvard Munch","Expressionismus","Klaus A. Schr\u00f6der","Lebensgef\u00fchl in der Moderne","Miriam Cahn und Peter Doig","Panik","Schrecken","St\u00e9phane Courtois","Verbrechen des Kommunismus"],"articleSection":["J\u00dcNGSTE BEITR\u00c4GE","Medien und Bildung \/ Religion","Studien \/ Rezensionen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/","url":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/","name":"Angstgef\u00fchle und Panik in der Moderne | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2022-05-01T08:52:56+00:00","dateModified":"2022-05-02T16:51:58+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/angst-in-moderne-fulminante-edvard-much-ausstellung-in-wien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Angstgef\u00fchle und Panik in der Moderne"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/10893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=10893"}],"version-history":[{"count":7,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/10893\/revisions"}],"predecessor-version":[{"id":10909,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/10893\/revisions\/10909"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=10893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=10893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=10893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}