{"id":10612,"date":"2022-02-01T10:52:50","date_gmt":"2022-02-01T09:52:50","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=10612"},"modified":"2022-02-01T18:59:19","modified_gmt":"2022-02-01T17:59:19","slug":"olympiade-und-englands-geschichte","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/","title":{"rendered":"Olympiade und Englands Geschichte"},"content":{"rendered":"<p>Party-G`schichterln oder Geschichte Englands<\/p>\n<p>Hans H\u00f6gl: Buchrezension <\/p>\n<p>Es dient dem V\u00f6lkerverst\u00e4ndnis, sich mit Landeskunde zu befassen, so auch mit England  und nicht nur mit Party &#8211; G`schichterln. Dem kommt nach &#8211; und zwar  hervorragend &#8211; das Taschenbuch &#8222;Die k\u00fcrzeste Geschichte Englands&#8220; von James Hawes, Berlin 2021. Der Autor erschlie\u00dft uns sein Land, zeigt Hintergr\u00fcnde und weithin unbekannte Details. Ich las das Buch nicht nur quer, wie manche Rezensenten, und deute Inhalte an: <\/p>\n<p>&#8212; dass wir von der genetischen Herkunft der Briten erfahren;<br \/>\n&#8212;dass am englischen Hofe 400 Jahre franz\u00f6sisch gesprochen wurde;<br \/>\n&#8212; dass schon seit 1589  der  s\u00fcd-englische Akzent Privilegien erfuhr und Autoren das Nord-Englisch meiden. Spannung und Kluft von S\u00fcd-zu Nordengland bis Heute.    <\/p>\n<p>&#8230; dass Karl Marx in England die Extremversion des Marktliberalismus erfuhr, und er schuf &#8211; in Kenntnis eines weltumspannenden britischen Imperiums &#8211; die Fantasie einer weltumspannenden sozialistischen Revolution (S. 236); <\/p>\n<p>&#8211;  dass wegen der deutschen Kriegsflotte die Zeitung &#8222;Daily Mail&#8220; schon im Jahr 1906 (!)- also 8 Jahre vor dem Ausbruch des 1.Weltkrieges &#8211;  den  Fortsetzungsroman &#8222;Die Invasion von 1910&#8220; brachte &#8211; mitsamt  Zeitungsverk\u00e4ufern in preu\u00dfischen Uniformen und falschen Landkarten  und mit Argumenten f\u00fcr die allgemeine Wehrpflicht (S. 273);   <\/p>\n<p>Und erinnern wir uns: 1920 waren Deutschland, \u00d6sterreich, Ungarn und die T\u00fcrkei infolge des Ersten Weltkriegs zu den Olympischen Spielen nicht eingeladen. Der Hintergrund: die  Schuld am 1. Weltkrieg&#8230;.. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Party-G`schichterln oder Geschichte Englands Hans H\u00f6gl: Buchrezension Es dient dem V\u00f6lkerverst\u00e4ndnis, sich mit Landeskunde zu befassen, so auch mit England und nicht nur mit Party &#8211; G`schichterln. Dem kommt nach &#8211; und zwar hervorragend &#8211; das Taschenbuch &#8222;Die k\u00fcrzeste Geschichte Englands&#8220; von James Hawes, Berlin 2021. Der Autor erschlie\u00dft uns sein Land, zeigt Hintergr\u00fcnde und &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/\" class=\"more-link\"><span class=\"screen-reader-text\">Olympiade und Englands Geschichte<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,24,12,11,10,23,19],"tags":[8367,8364,8371,8366,8368,2976,8372,8373,8369,8365,8370],"class_list":["post-10612","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-medien-universitaet","category-medien_bildung_religion","category-medien_politik_wirtschaft","category-medienkritik","category-medienschmankerl","category-studien_rezensionen","tag-buch-die-kuerzeste-geschichte-englands","tag-deutschland-und-olympiade","tag-franzoesisch-am-englischen-hof","tag-genanalyse-der-briten","tag-james-hawes","tag-karl-marx","tag-landeskunde","tag-nationgeschichte","tag-party-gschichterln","tag-sued-englisch","tag-ullstein-taschenbuch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Olympiade und Englands Geschichte | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olympiade und Englands Geschichte | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"Party-G`schichterln oder Geschichte Englands Hans H\u00f6gl: Buchrezension Es dient dem V\u00f6lkerverst\u00e4ndnis, sich mit Landeskunde zu befassen, so auch mit England und nicht nur mit Party &#8211; G`schichterln. Dem kommt nach &#8211; und zwar hervorragend &#8211; das Taschenbuch &#8222;Die k\u00fcrzeste Geschichte Englands&#8220; von James Hawes, Berlin 2021. Der Autor erschlie\u00dft uns sein Land, zeigt Hintergr\u00fcnde und &hellip; Olympiade und Englands Geschichte weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-01T09:52:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-01T17:59:19+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/olympiade-und-englands-geschichte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/olympiade-und-englands-geschichte\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"Olympiade und Englands Geschichte\",\"datePublished\":\"2022-02-01T09:52:50+00:00\",\"dateModified\":\"2022-02-01T17:59:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/olympiade-und-englands-geschichte\\\/\"},\"wordCount\":230,\"commentCount\":0,\"keywords\":[\"Buch: \\\"Die k\u00fcrzeste Geschichte Englands\\\"\",\"Deutschland und Olympiade\",\"Franz\u00f6sisch am englischen Hof\",\"Genanalyse der Briten\",\"James Hawes\",\"Karl Marx\",\"Landeskunde\",\"Nationgeschichte\",\"Party-G`schichterln\",\"S\u00fcd-Englisch\",\"Ullstein Taschenbuch\"],\"articleSection\":[\"J\u00dcNGSTE BEITR\u00c4GE\",\"MEDIEN - UNIVERSIT\u00c4T\",\"Medien und Bildung \\\/ Religion\",\"Medien und Politik \\\/ Wirtschaft\",\"Medienkritik\",\"Medienschmankerl\",\"Studien \\\/ Rezensionen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/olympiade-und-englands-geschichte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/olympiade-und-englands-geschichte\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/olympiade-und-englands-geschichte\\\/\",\"name\":\"Olympiade und Englands Geschichte | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2022-02-01T09:52:50+00:00\",\"dateModified\":\"2022-02-01T17:59:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/olympiade-und-englands-geschichte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/olympiade-und-englands-geschichte\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/olympiade-und-englands-geschichte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Olympiade und Englands Geschichte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olympiade und Englands Geschichte | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/","og_locale":"de_DE","og_type":"article","og_title":"Olympiade und Englands Geschichte | Vereinigung f\u00fcr Medienkultur","og_description":"Party-G`schichterln oder Geschichte Englands Hans H\u00f6gl: Buchrezension Es dient dem V\u00f6lkerverst\u00e4ndnis, sich mit Landeskunde zu befassen, so auch mit England und nicht nur mit Party &#8211; G`schichterln. Dem kommt nach &#8211; und zwar hervorragend &#8211; das Taschenbuch &#8222;Die k\u00fcrzeste Geschichte Englands&#8220; von James Hawes, Berlin 2021. Der Autor erschlie\u00dft uns sein Land, zeigt Hintergr\u00fcnde und &hellip; Olympiade und Englands Geschichte weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2022-02-01T09:52:50+00:00","article_modified_time":"2022-02-01T17:59:19+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"Olympiade und Englands Geschichte","datePublished":"2022-02-01T09:52:50+00:00","dateModified":"2022-02-01T17:59:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/"},"wordCount":230,"commentCount":0,"keywords":["Buch: \"Die k\u00fcrzeste Geschichte Englands\"","Deutschland und Olympiade","Franz\u00f6sisch am englischen Hof","Genanalyse der Briten","James Hawes","Karl Marx","Landeskunde","Nationgeschichte","Party-G`schichterln","S\u00fcd-Englisch","Ullstein Taschenbuch"],"articleSection":["J\u00dcNGSTE BEITR\u00c4GE","MEDIEN - UNIVERSIT\u00c4T","Medien und Bildung \/ Religion","Medien und Politik \/ Wirtschaft","Medienkritik","Medienschmankerl","Studien \/ Rezensionen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/","url":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/","name":"Olympiade und Englands Geschichte | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2022-02-01T09:52:50+00:00","dateModified":"2022-02-01T17:59:19+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/olympiade-und-englands-geschichte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Olympiade und Englands Geschichte"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/10612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=10612"}],"version-history":[{"count":10,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/10612\/revisions"}],"predecessor-version":[{"id":10626,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/10612\/revisions\/10626"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=10612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=10612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=10612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}