{"id":10604,"date":"2022-01-29T09:45:12","date_gmt":"2022-01-29T08:45:12","guid":{"rendered":"http:\/\/www.medienkultur.at\/neu\/?p=10604"},"modified":"2022-01-29T09:46:01","modified_gmt":"2022-01-29T08:46:01","slug":"erschreckende-ueberwachung","status":"publish","type":"post","link":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/","title":{"rendered":"Erschreckende \u00dcberwachung"},"content":{"rendered":"<p>Pr\u00e4gnante Aussagen zur \u00dcberwachung von Personen durch Algorithmen<\/p>\n<p>Hans H\u00f6gl<\/p>\n<p>Wer es ausf\u00fchrlicher dazu w\u00fcnscht, lese hunderte Seiten in den B\u00fcchern von dem au\u00dfergew\u00f6hnlichen Autor Yuval Harari. Hier aber eine K\u00fcrzestversion, die alles auf einen Punkt bringt.<\/p>\n<p>Indem wir Computer und Smartphones nutzen, liefern wir zahlreiche Informationen \u00fcber uns ins Netz. Daraus entsteht ein detailliertes Profil \u00fcber unsere Handlungen, W\u00fcnsche und Bewegungen. Algorithmen und k\u00fcnstliche Intelligenz filtern aus den Daten Zusammenh\u00e4nge heraus, was immer genauere R\u00fcckschl\u00fcsse auf unser Verhalten erm\u00f6glicht. Diese Programme wissen oft mehr \u00fcber uns, als uns selbst bewusst ist. Sie k\u00f6nnen voraussagen, wie wir handeln, und so unsere Entscheidungen, etwa beim Online-Einkauf und bei Wahlen, beeinflussen. Haben wir \u00fcberhaupt noch eine Privatsph\u00e4re? F\u00fcr \u00abNZZ Format\u00bb hat unser Autor Reto Caduff Sicherheitsexperten, Datenspezialistinnen und Hacker gefragt, wie man sich sch\u00fctzen kann. Zum Video. (Quelle.Nzz online 29.1.2022)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e4gnante Aussagen zur \u00dcberwachung von Personen durch Algorithmen Hans H\u00f6gl Wer es ausf\u00fchrlicher dazu w\u00fcnscht, lese hunderte Seiten in den B\u00fcchern von dem au\u00dfergew\u00f6hnlichen Autor Yuval Harari. Hier aber eine K\u00fcrzestversion, die alles auf einen Punkt bringt. Indem wir Computer und Smartphones nutzen, liefern wir zahlreiche Informationen \u00fcber uns ins Netz. Daraus entsteht ein detailliertes &hellip; <a href=\"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/\" class=\"more-link\"><span class=\"screen-reader-text\">Erschreckende \u00dcberwachung<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,12,18,10,23,19],"tags":[2477,8356,8358,8357,4277,8355,8354,4122,1652],"class_list":["post-10604","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-medien_bildung_religion","category-medienkompetenz","category-medienkritik","category-medienschmankerl","category-studien_rezensionen","tag-algorithmen","tag-computer","tag-digitale-welt","tag-e-mails","tag-kuenstliche-intelligenz","tag-privatsphaere","tag-profil-von-personen","tag-smartphones","tag-ueberwachung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erschreckende \u00dcberwachung | Vereinigung f\u00fcr Medienkultur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erschreckende \u00dcberwachung | Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"og:description\" content=\"Pr\u00e4gnante Aussagen zur \u00dcberwachung von Personen durch Algorithmen Hans H\u00f6gl Wer es ausf\u00fchrlicher dazu w\u00fcnscht, lese hunderte Seiten in den B\u00fcchern von dem au\u00dfergew\u00f6hnlichen Autor Yuval Harari. Hier aber eine K\u00fcrzestversion, die alles auf einen Punkt bringt. Indem wir Computer und Smartphones nutzen, liefern wir zahlreiche Informationen \u00fcber uns ins Netz. Daraus entsteht ein detailliertes &hellip; Erschreckende \u00dcberwachung weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/\" \/>\n<meta property=\"og:site_name\" content=\"Vereinigung f\u00fcr Medienkultur\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-29T08:45:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-29T08:46:01+00:00\" \/>\n<meta name=\"author\" content=\"Hans H\u00f6gl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hans H\u00f6gl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/erschreckende-ueberwachung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/erschreckende-ueberwachung\\\/\"},\"author\":{\"name\":\"Hans H\u00f6gl\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"headline\":\"Erschreckende \u00dcberwachung\",\"datePublished\":\"2022-01-29T08:45:12+00:00\",\"dateModified\":\"2022-01-29T08:46:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/erschreckende-ueberwachung\\\/\"},\"wordCount\":158,\"commentCount\":0,\"keywords\":[\"Algorithmen\",\"Computer\",\"Digitale Welt\",\"E-Mails\",\"K\u00fcnstliche Intelligenz\",\"Privatsph\u00e4re\",\"Profil von Personen\",\"Smartphones\",\"\u00dcberwachung\"],\"articleSection\":[\"J\u00dcNGSTE BEITR\u00c4GE\",\"Medien und Bildung \\\/ Religion\",\"Medienkompetenz\",\"Medienkritik\",\"Medienschmankerl\",\"Studien \\\/ Rezensionen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/erschreckende-ueberwachung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/erschreckende-ueberwachung\\\/\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/erschreckende-ueberwachung\\\/\",\"name\":\"Erschreckende \u00dcberwachung | Vereinigung f\u00fcr Medienkultur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\"},\"datePublished\":\"2022-01-29T08:45:12+00:00\",\"dateModified\":\"2022-01-29T08:46:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/erschreckende-ueberwachung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/erschreckende-ueberwachung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/erschreckende-ueberwachung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erschreckende \u00dcberwachung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#website\",\"url\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/\",\"name\":\"Vereinigung f\u00fcr Medienkultur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.medienkultur.at\\\/neu\\\/#\\\/schema\\\/person\\\/5307830ec125174672d8c9d829eeb256\",\"name\":\"Hans H\u00f6gl\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erschreckende \u00dcberwachung | Vereinigung f\u00fcr Medienkultur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/","og_locale":"de_DE","og_type":"article","og_title":"Erschreckende \u00dcberwachung | Vereinigung f\u00fcr Medienkultur","og_description":"Pr\u00e4gnante Aussagen zur \u00dcberwachung von Personen durch Algorithmen Hans H\u00f6gl Wer es ausf\u00fchrlicher dazu w\u00fcnscht, lese hunderte Seiten in den B\u00fcchern von dem au\u00dfergew\u00f6hnlichen Autor Yuval Harari. Hier aber eine K\u00fcrzestversion, die alles auf einen Punkt bringt. Indem wir Computer und Smartphones nutzen, liefern wir zahlreiche Informationen \u00fcber uns ins Netz. Daraus entsteht ein detailliertes &hellip; Erschreckende \u00dcberwachung weiterlesen &rarr;","og_url":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/","og_site_name":"Vereinigung f\u00fcr Medienkultur","article_published_time":"2022-01-29T08:45:12+00:00","article_modified_time":"2022-01-29T08:46:01+00:00","author":"Hans H\u00f6gl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hans H\u00f6gl","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/#article","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/"},"author":{"name":"Hans H\u00f6gl","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"headline":"Erschreckende \u00dcberwachung","datePublished":"2022-01-29T08:45:12+00:00","dateModified":"2022-01-29T08:46:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/"},"wordCount":158,"commentCount":0,"keywords":["Algorithmen","Computer","Digitale Welt","E-Mails","K\u00fcnstliche Intelligenz","Privatsph\u00e4re","Profil von Personen","Smartphones","\u00dcberwachung"],"articleSection":["J\u00dcNGSTE BEITR\u00c4GE","Medien und Bildung \/ Religion","Medienkompetenz","Medienkritik","Medienschmankerl","Studien \/ Rezensionen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/","url":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/","name":"Erschreckende \u00dcberwachung | Vereinigung f\u00fcr Medienkultur","isPartOf":{"@id":"https:\/\/www.medienkultur.at\/neu\/#website"},"datePublished":"2022-01-29T08:45:12+00:00","dateModified":"2022-01-29T08:46:01+00:00","author":{"@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256"},"breadcrumb":{"@id":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.medienkultur.at\/neu\/erschreckende-ueberwachung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.medienkultur.at\/neu\/"},{"@type":"ListItem","position":2,"name":"Erschreckende \u00dcberwachung"}]},{"@type":"WebSite","@id":"https:\/\/www.medienkultur.at\/neu\/#website","url":"https:\/\/www.medienkultur.at\/neu\/","name":"Vereinigung f\u00fcr Medienkultur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.medienkultur.at\/neu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.medienkultur.at\/neu\/#\/schema\/person\/5307830ec125174672d8c9d829eeb256","name":"Hans H\u00f6gl"}]}},"_links":{"self":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/10604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/comments?post=10604"}],"version-history":[{"count":1,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/10604\/revisions"}],"predecessor-version":[{"id":10605,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/posts\/10604\/revisions\/10605"}],"wp:attachment":[{"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/media?parent=10604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/categories?post=10604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.medienkultur.at\/neu\/wp-json\/wp\/v2\/tags?post=10604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}